{"id":468101,"date":"2026-05-11T14:18:54","date_gmt":"2026-05-11T14:18:54","guid":{"rendered":"https:\/\/admin.industriall-union.org\/?post_type=article&#038;p=468101"},"modified":"2026-05-13T15:03:55","modified_gmt":"2026-05-13T15:03:55","slug":"acquisition-kone-tk-elevator-droits-travailleurs","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/","title":{"rendered":"M\u00e9ga-accord entre KONE et TK Elevator\u00a0: les travailleurs derniers inform\u00e9s"},"content":{"rendered":"\n<p>Si elle \u00e9tait approuv\u00e9e par les autorit\u00e9s de r\u00e9gulation, cette acquisition, la plus marquante de l\u2019histoire des entreprises finlandaises et l\u2019un des d\u00e9sengagements de capitaux priv\u00e9s majeurs en Europe, donnerait naissance au plus grand fabricant d\u2019ascenseurs et d\u2019escaliers m\u00e9caniques au monde. Les principaux sujets de discussion portent sur la prise de contr\u00f4le de TK Elevator par KONE et ses effets potentiels sur les droits des travailleuses et travailleurs. Par cette op\u00e9ration, la multinationale emploierait plus de 100.000 salari\u00e9s dans plus de 100 pays diff\u00e9rents.<\/p>\n\n\n\n<p>Les travailleuses, les travailleurs et leurs repr\u00e9sentants ont appris la nouvelle en m\u00eame temps que le reste du monde, par la presse financi\u00e8re. Le PDG leur a, par ailleurs, adress\u00e9 un e-mail pour les informer une fois l\u2019annonce publi\u00e9e.<\/p>\n\n\n\n<p>C&#8217;est inadmissible. Ce communiqu\u00e9 constitue une grave violation de l&#8217;accord-cadre sign\u00e9 en 2021 entre TK Elevator, le Comit\u00e9 d&#8217;entreprise du groupe, IG Metall et IndustriALL. TKE elle-m\u00eame consid\u00e8re ce texte comme un garde-fou essentiel pour la protection des droits humains et des droits des travailleurs \u00e0 l&#8217;\u00e9chelle mondiale. De plus, elle viole clairement les accords du CEE et du Conseil mondial des travailleurs, sign\u00e9s respectivement en 2022 et 2024. Ceux-ci \u00e9tablissent des droits \u00e0 l&#8217;information et \u00e0 la consultation.<strong><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-une-confiance-trahie\"><strong>Une confiance trahie<\/strong><\/h2>\n\n\n\n<p>La r\u00e9action des repr\u00e9sentants syndicaux a \u00e9t\u00e9 imm\u00e9diate et sans aucune ambigu\u00eft\u00e9. Knut Giesler, Vice-pr\u00e9sident du Conseil de surveillance de TKE et Responsable r\u00e9gional d\u2019IG Metall pour la Rh\u00e9nanie-du-Nord-Westphalie, a qualifi\u00e9 cette annonce de scandaleuse. Il l\u2019a en outre qualifi\u00e9e d\u2019attaque directe contre les droits de cogestion des travailleuses et travailleurs en Allemagne, en Europe et dans le monde. IG Metall a exig\u00e9 la tenue d\u2019une r\u00e9union extraordinaire du Conseil de surveillance de la soci\u00e9t\u00e9.<\/p>\n\n\n\n<p>Dans le jargon propre aux march\u00e9s financiers, les 700 millions d\u2019euros (824 millions de dollars) de synergies annuelles pr\u00e9vues signifient tout bonnement des suppressions d\u2019emplois. Cela repr\u00e9sente une menace directe pour des dizaines de milliers de salari\u00e9s de TKE \u00e0 travers le monde.<\/p>\n\n\n\n<p>Christiane Benner, Pr\u00e9sidente d\u2019IG Metall et d\u2019IndustriALL&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab&nbsp;La cession de TK Elevator \u00e0 KONE ne doit pas se faire au d\u00e9triment des salari\u00e9s. Nous n\u2019accepterons pas le sacrifice de milliers d\u2019emplois de qualit\u00e9 sous le pr\u00e9texte de synergies. Quiconque soutient cette fusion doit \u00e9galement garantir la pr\u00e9servation des emplois et des implantations, le respect de la cogestion et la cr\u00e9ation d\u2019opportunit\u00e9s pour le personnel. Toute autre issue se heurtera \u00e0 une opposition inflexible de notre part.&nbsp;\u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Et c\u2019est pourquoi nous nous battrons pour que&nbsp;:<\/p>\n\n\n\n<p>Aucun site ne soit isol\u00e9.<\/p>\n\n\n\n<p>Aucun pays ne soit oppos\u00e9 \u00e0 un autre.<\/p>\n\n\n\n<p>Aucun salari\u00e9 ne soit laiss\u00e9 pour compte.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab&nbsp;D\u2019un point de vue europ\u00e9en, cette annonce constitue une violation flagrante tant de l\u2019esprit que de la lettre des accords du Comit\u00e9 d\u2019entreprise europ\u00e9en chez KONE et chez TK Elevator. Plus de 45.000 travailleuses et travailleurs en Europe sont directement concern\u00e9s par ce projet d\u2019acquisition et pourtant leurs repr\u00e9sentants \u00e9lus ont \u00e9t\u00e9 compl\u00e8tement mis \u00e0 l\u2019\u00e9cart. C\u2019est inacceptable. Avant que toute nouvelle mesure ne soit prise, KONE et TK Elevator doivent se conformer pleinement \u00e0 leurs obligations existantes en mati\u00e8re d\u2019information et de consultation. Si cette op\u00e9ration doit se poursuivre, elle doit s\u2019inscrire dans un projet de croissance qui profite \u00e9galement aux salari\u00e9s, gr\u00e2ce \u00e0 la s\u00e9curit\u00e9 de l\u2019emploi, au respect de la n\u00e9gociation collective ainsi qu\u2019\u00e0 une information et une consultation pr\u00e9alables et compl\u00e8tes&nbsp;\u00bb<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>a d\u00e9clar\u00e9 Judith Kirton-Darling, Secr\u00e9taire g\u00e9n\u00e9rale d\u2019industriAll Europe.<strong><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-question-a-laquelle-kone-doit-repondre\"><strong>La question \u00e0 laquelle KONE doit r\u00e9pondre<\/strong><\/h2>\n\n\n\n<p>KONE n\u2019a pris aucun engagement public quant au respect des accords existants de TKE. L\u2019entit\u00e9 issue de la fusion aura son si\u00e8ge en Finlande. L\u2019architecture actuelle de cogestion de TK Elevator comprend la structure du Conseil de surveillance, le Comit\u00e9 d\u2019entreprise du groupe, le Comit\u00e9 d\u2019entreprise europ\u00e9en, le Conseil mondial des travailleurs ainsi que l\u2019accord-cadre mondial (ACM) lui-m\u00eame. Cependant, son avenir semble incertain sous la nouvelle direction \u00e0 moins que KONE n\u2019assume toutes ces obligations de mani\u00e8re formelle et explicite.<\/p>\n\n\n\n<p>Le Secr\u00e9taire g\u00e9n\u00e9ral d\u2019IndustriALL, Atle Hoie, a d\u00e9clar\u00e9&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab&nbsp;L\u2019annonce de l\u2019acquisition de TK Elevator par KONE constitue une violation directe de l\u2019ACM et de l\u2019accord avec le Conseil mondial des travailleurs sign\u00e9s entre IndustriALL et TK Elevator en 2021 et 2024. Loin d\u2019une simple formalit\u00e9, ceux-ci instaurent l\u2019engagement contraignant de consulter les travailleuses et travailleurs avant que des d\u00e9cisions de cette ampleur ne soient prises et non \u00e0 posteriori. Plus de 100.000 membres du personnel \u00e0 travers le monde ont appris le plus grand changement de l\u2019histoire des deux entreprises par la presse financi\u00e8re. C\u2019est intol\u00e9rable. Il n\u2019y aura aucune coop\u00e9ration syndicale dans le cadre de cette transaction \u00e0 moins que nos accords ne soient pleinement respect\u00e9s.&nbsp;\u00bb<\/em><strong><\/strong><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-une-action-immediate\"><strong>Une action imm\u00e9diate<\/strong><\/h2>\n\n\n\n<p>IndustriALL et industriAll Europe coordonnent leurs efforts avec leurs affili\u00e9s, notamment IG Metall et les membres finlandais, pour garantir que les travailleuses et travailleurs des deux parties prenantes \u00e0 cette transaction aient leur mot \u00e0 dire.<\/p>\n\n\n\n<p>Le processus d\u2019examen antitrust devrait durer au moins jusqu\u2019\u00e0 la mi-2027. Ce d\u00e9lai ne fait pas uniquement r\u00e9f\u00e9rence \u00e0 une d\u00e9marche r\u00e9glementaire ; il est \u00e0 prendre comme une opportunit\u00e9. Durant cette p\u00e9riode, les syndicats n\u2019auront de cesse de se battre chaque jour pour leurs emplois.<\/p>\n\n\n\n<p>Une soci\u00e9t\u00e9 d\u2019investissement priv\u00e9 a rachet\u00e9 TK Elevator en 2020. La main-d\u2019\u0153uvre a d\u00e9j\u00e0 pay\u00e9 le prix de cette transition. Elle ne sera pas une nouvelle fois laiss\u00e9e pour compte.<\/p>\n\n\n\n<p>La plus grande entreprise mondiale d\u2019ascenseurs ne devrait pas se construire sur le dos de salari\u00e9s qui n\u2019ont jamais \u00e9t\u00e9 consult\u00e9s.<\/p>\n\n\n\n<p>Ceux-ci ne sont pas l\u2019objet de cet accord, ils en sont le fondement. Au bout du compte, ce sont eux qui ont cr\u00e9\u00e9 la valeur et ils doivent \u00eatre trait\u00e9s avec reconnaissance et respect.<\/p>\n","protected":false},"featured_media":0,"template":"","issues":[424,425],"companies":[],"regions":[216],"sectors":[481,475],"article_tags":[],"class_list":["post-468101","article","type-article","status-publish","hentry","issues-violation","issues-workers-rights","regions-finland","sectors-base-metals","sectors-mechanical-engineering"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Acquisition KONE TK Elevator : des droits des travailleur\u00b7euses bafou\u00e9s<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment l&#039;acquisition de TK Elevator par KONE affecte les droits des travailleur\u00b7euses et les accords cens\u00e9s les prot\u00e9ger.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9ga-accord entre KONE et TK Elevator\u00a0: les travailleurs derniers inform\u00e9s\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment l&#039;acquisition de TK Elevator par KONE affecte les droits des travailleur\u00b7euses et les accords cens\u00e9s les prot\u00e9ger.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T15:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/\",\"name\":\"Acquisition KONE TK Elevator : des droits des travailleur\u00b7euses bafou\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/#website\"},\"datePublished\":\"2026-05-11T14:18:54+00:00\",\"dateModified\":\"2026-05-13T15:03:55+00:00\",\"description\":\"D\u00e9couvrez comment l'acquisition de TK Elevator par KONE affecte les droits des travailleur\u00b7euses et les accords cens\u00e9s les prot\u00e9ger.\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/ru\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e9ga-accord entre KONE et TK Elevator\u00a0: les travailleurs derniers inform\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Acquisition KONE TK Elevator : des droits des travailleur\u00b7euses bafou\u00e9s","description":"D\u00e9couvrez comment l'acquisition de TK Elevator par KONE affecte les droits des travailleur\u00b7euses et les accords cens\u00e9s les prot\u00e9ger.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/","og_locale":"fr_FR","og_type":"article","og_title":"M\u00e9ga-accord entre KONE et TK Elevator\u00a0: les travailleurs derniers inform\u00e9s","og_description":"D\u00e9couvrez comment l'acquisition de TK Elevator par KONE affecte les droits des travailleur\u00b7euses et les accords cens\u00e9s les prot\u00e9ger.","og_url":"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/","og_site_name":"industriall-union","article_modified_time":"2026-05-13T15:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/","url":"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/","name":"Acquisition KONE TK Elevator : des droits des travailleur\u00b7euses bafou\u00e9s","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/#website"},"datePublished":"2026-05-11T14:18:54+00:00","dateModified":"2026-05-13T15:03:55+00:00","description":"D\u00e9couvrez comment l'acquisition de TK Elevator par KONE affecte les droits des travailleur\u00b7euses et les accords cens\u00e9s les prot\u00e9ger.","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/acquisition-kone-tk-elevator-droits-travailleurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/ru\/article\/"},{"@type":"ListItem","position":3,"name":"M\u00e9ga-accord entre KONE et TK Elevator\u00a0: les travailleurs derniers inform\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/#website","url":"https:\/\/admin.industriall-union.org\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/468101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=468101"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=468101"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=468101"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=468101"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=468101"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=468101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}