{"id":174590,"date":"2013-02-07T16:51:55","date_gmt":"2013-02-07T16:51:55","guid":{"rendered":"https:\/\/admin.industriall-union.org\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/"},"modified":"2025-02-08T15:15:08","modified_gmt":"2025-02-08T15:15:08","slug":"60-000-travailleurs-manifestent-dans-les-rues-de-mexico","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/","title":{"rendered":"60.000 travailleurs manifestent dans les rues de Mexico"},"content":{"rendered":"<p>Les 60.000 personnes qui s&rsquo;\u00e9taient mobilis\u00e9es ont d\u00e9nonc\u00e9 l&rsquo;injustice du jugement rendu par la Cour supr\u00eame du pays, le 30 janvier, contre le plus ancien syndicat d\u00e9mocratique du Mexique, le syndicat mexicain des \u00e9lectriciens (SME). Cette d\u00e9cision rejette le jugement de la Cour d&#039;appel prononc\u00e9 conform\u00e9ment \u00e0 la l\u00e9gislation nationale du travail qui implique clairement la responsabilit\u00e9 patronale d&#039;une entreprise charg\u00e9e de mener des activit\u00e9s pour le compte d&rsquo;une autre entreprise, comme ce fut le cas pour des membres du SME. Il est difficile d&#039;interpr\u00e9ter ce jugement injuste de la Cour supr\u00eame, contraire \u00e0 la l\u00e9gislation mexicaine, sinon comme un effort entrepris par l&#039;\u00e9lite au pouvoir pour mettre \u00e0 bas le syndicat des \u00e9lectriciens (SME): <a href=\"http:\/\/www.industriall-union.org\/mexicos-supreme-court-unfairly-rules-against-sme\">http:\/\/www.industriall-union.org\/mexicos-supreme-court-unfairly-rules-against-sme<\/a>.<\/p><p>Dans une allocution prononc\u00e9e lors de la manifestation qui a atteint son apog\u00e9e sur la Plaza Z\u00f3calo, le secr\u00e9taire g\u00e9n\u00e9ral du SME, Mart\u00edn Esparza, a demand\u00e9 aux manifestants s&rsquo;ils acceptaient la d\u00e9cision de la Cour supr\u00eame et tiraient un trait sur leurs trois ann\u00e9es de lutte pour leur r\u00e9int\u00e9gration. La foule a r\u00e9pondu par un &ldquo;NON&rdquo; massif&nbsp; et unanime.<\/p><p>La pression commence \u00e0 s&#039;exercer sur le nouveau pr\u00e9sident Enrique Pe\u00f1a Nieto pour emp\u00eacher que son parti, le PRI, qui a pris en main le gouvernement, continue d&#039;appliquer la politique r\u00e9pressive du gouvernement pr\u00e9c\u00e9dent du parti PAN pour r\u00e9primer les mouvements sociaux au nom de l&#039;ordre \u00e9tabli.<\/p><p>Un appel identique pour obtenir des changements a \u00e9t\u00e9 lanc\u00e9 dans une <a href=\"\/wp-content\/uploads\/documents\/Mexico2013\/globalunions_letter_mexico_feb2013_0.pdf\">lettre au pr\u00e9sident du Mexique<\/a>, envoy\u00e9e le 6 f\u00e9vrier 2013 par la Conf\u00e9d\u00e9ration syndicale internationale (CSI) et tous les syndicats mondiaux.<\/p><p>Le terrain est pr\u00e9par\u00e9 pour les fortes journ\u00e9es mondiales d&#039;action pour les droits des travailleurs et travailleuses au Mexique qui auront lieu du 18 au 24 f\u00e9vrier. Les affili\u00e9s de IndustriALL Global Union dans le monde se joignent aux syndicalistes des autres secteurs pour manifester l&rsquo;indignation internationale contre des pratiques antisyndicale concert\u00e9es au Mexique.<\/p><p>L&#039;action unifi\u00e9e au Mexique sera men\u00e9e par tous les syndicats nationaux d\u00e9mocratiques avec le soutien de leurs coll\u00e8gues internationaux. Parmi les actions entreprises, il y aura une conf\u00e9rence de presse conjointe, un rassemblement public, des visites d&#039;ambassades, une caravane de solidarit\u00e9, une marche silencieuse de comm\u00e9moration \u00e0 la m\u00e9moire des victimes de Pasta de Conchos, et un d\u00e9fil\u00e9 de grande envergure dans la capitale.<\/p><p>L&#039;alliance de solidarit\u00e9 tri-nationale des syndicats au Canada, au Mexique et aux \u00c9tats-Unis joue un r\u00f4le d\u00e9terminant dans les activit\u00e9s pr\u00e9vues \u00e0 Austin, Boston, Chicago, Denver, Detroit, Houston, Indianapolis, Kansas City, Los Angeles, Miami, Montr\u00e9al, la Nouvelle-Orl\u00e9ans, New York, Ottawa, Portland, Raleigh, Seattle, Tucson, Vancouver et Washington DC.&nbsp;<\/p><p>Unite the Union au Royaume-Uni organise une <a href=\"http:\/\/www.industriall-union.org\/stop-attacks-on-trade-unions-in-mexico\">r\u00e9union publique<\/a> le 20 f\u00e9vrier avec le TUC et d&#039;autres groupes.<\/p><p>Prendre connaissance ici de la lettre conjointe en date du 6 f\u00e9vrier, envoy\u00e9e au pr\u00e9sident Enrique Pe\u00f1a Nieto par la Conf\u00e9d\u00e9ration syndicale internationale (CSI) et toutes les f\u00e9d\u00e9rations syndicales internationales.<\/p><p>Les quatre revendications principales des journ\u00e9es mondiales d&#039;action 2013 sont les suivantes:<\/p><ul><li>Justice pour les familles des 65 mineurs tu\u00e9s \u00e0 Pasta de Conchos le 19 f\u00e9vrier 2006.<\/li><li>Fin des contrats de protection sous la coupe de l&#039;employeur qui privent les travailleurs et travailleuses du droit \u00e0 une repr\u00e9sentation d\u00e9mocratique et \u00e0 la n\u00e9gociation collective.<\/li><li>Abrogation de la Loi sur le travail promulgu\u00e9e le 1<sup>er<\/sup> d\u00e9cembre 2012 qui favorise le licenciement d&#039;activistes syndicaux, intensifie la sous-traitance et conduit \u00e0 une extension massive de l&#039;emploi pr\u00e9caire.<\/li><li>R\u00e9int\u00e9gration des activistes syndicaux mis \u00e0 pied ill\u00e9galement de SME, PKC, Vidriera de Potosi\/Grupo Modelo; Honda; Calzado Sandak \/Bata, et \u00e9lections libres et impartiales chez PKC, Excellon, Honda, Atento.<\/li><\/ul><p>Engagez-vous, entreprenez une action et suivez la campagne sur le site de IndustriALL <a href=\"http:\/\/www.industriall-union.org\/mexico-campaign\">ici<\/a>. Vous y trouverez du mat\u00e9riel de campagne, de nouvelles vid\u00e9os, et de nouvelles fa\u00e7ons d&#039;entreprendre une action pour soutenir la campagne au cours des prochaines semaines.<\/p><p><a href=\"http:\/\/www.industriall-union.org\/mexico-campaign\">www.industriall-union.org\/mexico-campaign<\/a><\/p>","protected":false},"featured_media":0,"template":"","issues":[421,420,425],"companies":[],"regions":[275],"sectors":[483],"article_tags":[],"class_list":["post-174590","article","type-article","status-publish","hentry","issues-mexico-campaign","issues-solidarity","issues-workers-rights","regions-mexico","sectors-energy-oil-gas-electricity-and-nuclear"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>60.000 travailleurs manifestent dans les rues de Mexico - industriall-union<\/title>\n<meta name=\"description\" content=\"Les 60.000 personnes qui s&rsquo;\u00e9taient mobilis\u00e9es ont d\u00e9nonc\u00e9 l&rsquo;injustice du jugement rendu par la Cour supr\u00eame du pays, le 30 janvier, contre le\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"60.000 travailleurs manifestent dans les rues de Mexico\" \/>\n<meta property=\"og:description\" content=\"Les 60.000 personnes qui s&rsquo;\u00e9taient mobilis\u00e9es ont d\u00e9nonc\u00e9 l&rsquo;injustice du jugement rendu par la Cour supr\u00eame du pays, le 30 janvier, contre le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-08T15:15:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/\",\"name\":\"60.000 travailleurs manifestent dans les rues de Mexico - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2013-02-07T16:51:55+00:00\",\"dateModified\":\"2025-02-08T15:15:08+00:00\",\"description\":\"Les 60.000 personnes qui s&rsquo;\u00e9taient mobilis\u00e9es ont d\u00e9nonc\u00e9 l&rsquo;injustice du jugement rendu par la Cour supr\u00eame du pays, le 30 janvier, contre le\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"60.000 travailleurs manifestent dans les rues de Mexico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"60.000 travailleurs manifestent dans les rues de Mexico - industriall-union","description":"Les 60.000 personnes qui s&rsquo;\u00e9taient mobilis\u00e9es ont d\u00e9nonc\u00e9 l&rsquo;injustice du jugement rendu par la Cour supr\u00eame du pays, le 30 janvier, contre le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/","og_locale":"fr_FR","og_type":"article","og_title":"60.000 travailleurs manifestent dans les rues de Mexico","og_description":"Les 60.000 personnes qui s&rsquo;\u00e9taient mobilis\u00e9es ont d\u00e9nonc\u00e9 l&rsquo;injustice du jugement rendu par la Cour supr\u00eame du pays, le 30 janvier, contre le","og_url":"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/","og_site_name":"industriall-union","article_modified_time":"2025-02-08T15:15:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/","url":"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/","name":"60.000 travailleurs manifestent dans les rues de Mexico - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2013-02-07T16:51:55+00:00","dateModified":"2025-02-08T15:15:08+00:00","description":"Les 60.000 personnes qui s&rsquo;\u00e9taient mobilis\u00e9es ont d\u00e9nonc\u00e9 l&rsquo;injustice du jugement rendu par la Cour supr\u00eame du pays, le 30 janvier, contre le","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/60-000-travailleurs-manifestent-dans-les-rues-de-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/fr\/article\/"},{"@type":"ListItem","position":3,"name":"60.000 travailleurs manifestent dans les rues de Mexico"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/174590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=174590"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=174590"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=174590"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=174590"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=174590"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=174590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}