{"id":174523,"date":"2013-02-18T14:47:31","date_gmt":"2013-02-18T14:47:31","guid":{"rendered":"https:\/\/admin.industriall-union.org\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/"},"modified":"2025-02-08T14:52:30","modified_gmt":"2025-02-08T14:52:30","slug":"les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/","title":{"rendered":"Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes"},"content":{"rendered":"<p>La campagne se base sur les statistiques selon lesquelles une femme sur trois sera victime dans tous les pays \u00e0 des violences au cours de sa vie, comme l&#039;explique le pr\u00e9sident international de l&rsquo;USW, Leo W. Gerard, dans cette vid\u00e9o. <a href=\"http:\/\/www.usw.org\/media_center\/news_articles?id=1301\">http:\/\/www.usw.org\/media_center\/news_articles?id=1301<\/a><\/p><p>Les actions de l&#039;association &ldquo;V-Day&rdquo; ont r\u00e9ussi \u00e0 mobiliser des communaut\u00e9s et \u00e0 \u00e9difier une solidarit\u00e9 mondiale entre les fronti\u00e8res et les races, en insistant sur les causes de la violence &ndash; patriarcat, pauvret\u00e9, cupidit\u00e9 des entreprises, d\u00e9gradation de l&#039;environnement, imp\u00e9rialisme, religion, militarisation, exil, r\u00e9pression politique. &rdquo;One Billion Rising&rdquo; assure qu&rsquo;une prise de conscience sur la question des violences faites aux femmes ne sera plus jamais ignor\u00e9e.<\/p><p>Les r\u00e9centes affaires qui ont attir\u00e9 l&#039;attention du public sur des meurtres en <a href=\"http:\/\/www.industriall-union.org\/fr\/des-millions-protestent-en-inde-contre-la-violence-dont-sont-victimes-les-femmes\">Inde<\/a> et en Afrique du Sud montrent bien que la question de la violence contre les femmes est omnipr\u00e9sente dans nos soci\u00e9t\u00e9s. La violence d&#039;un sexe sur l&#039;autre prend des formes diverses &ndash; violence domestique, s\u00e9vices sexuels, viol commis par une connaissance, s\u00e9vices sexuels inflig\u00e9s \u00e0 un enfant, viols &ldquo;correctifs&rdquo; en raison de l&rsquo;orientation sexuelle, viols collectifs, grossesse forc\u00e9e, crimes d&#039;honneur, jet d&rsquo;acide, mutilations g\u00e9nitales f\u00e9minines, mort pour cause de dot, violences et viols dans des conflits arm\u00e9s, trafic de femmes et de filles, harc\u00e8lement sexuel au travail, et la liste se poursuit. Malheureusement, dans de nombreux pays, la violence contre les femmes est en augmentation, et dans certains cas de mani\u00e8re exponentielle. Certains disent que la violence est aliment\u00e9e par la crise \u00e9conomique. Mais tant que les femmes ne pourront pas intervenir et ne seront pas prises au s\u00e9rieux, la violence ne diminuera pas.<\/p><p>Les meilleures lois au monde sont insuffisantes pour prot\u00e9ger les femmes de la violence. C&#039;est pourquoi la soci\u00e9t\u00e9 civile prend des initiatives comme &rdquo;One Billion Rising&rdquo; et les syndicats donnent la priorit\u00e9 \u00e0 la question de la violence contre les femmes. Ce que les syndicats peuvent faire, c&rsquo;est avant tout d&rsquo;\u00e9duquer leurs membres sur la violence domestique et sur le respect, en travaillant ensemble et en parrainant des refuges pour femmes battues, en incluant des clauses sur la violence dans les accords, en n\u00e9gociant des cong\u00e9s pour traiter les questions qui ont des r\u00e9percussions sur des membres qui souffrent de violence domestique, et surtout de cr\u00e9er une culture de tol\u00e9rance z\u00e9ro de la violence.<\/p><p>La Journ\u00e9e internationale de la femme qui a lieu le 8 mars est tr\u00e8s proche. La Conf\u00e9d\u00e9ration syndicale internationale met l&#039;accent cette ann\u00e9e sur la violence, et des travaux seront men\u00e9s \u00e0 la commission des Nations unies sur le statut des femmes pour \u00e9laborer des principes directeurs au niveau international pour combattre le fl\u00e9au de la violence contre les femmes. Nous vous demandons d&#039;entreprendre une action dans votre syndicat pour \u00e9duquer vos membres et lutter contre la violence. Envoyez des rapports sur vos activit\u00e9s organis\u00e9es le 8 mars ou un autre jour \u00e0 <a href=\"mailto:press@industriall-union.org\">press@industriall-union.org<\/a> en nous indiquant vos r\u00e9ussites.<\/p>","protected":false},"featured_media":0,"template":"","issues":[397],"companies":[],"regions":[],"sectors":[],"article_tags":[512,1701],"class_list":["post-174523","article","type-article","status-publish","hentry","issues-women","article_tags-international-womens-day","article_tags-international-womens-day-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes - industriall-union<\/title>\n<meta name=\"description\" content=\"La campagne se base sur les statistiques selon lesquelles une femme sur trois sera victime dans tous les pays \u00e0 des violences au cours de sa vie, comme\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes\" \/>\n<meta property=\"og:description\" content=\"La campagne se base sur les statistiques selon lesquelles une femme sur trois sera victime dans tous les pays \u00e0 des violences au cours de sa vie, comme\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-08T14:52:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/\",\"name\":\"Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2013-02-18T14:47:31+00:00\",\"dateModified\":\"2025-02-08T14:52:30+00:00\",\"description\":\"La campagne se base sur les statistiques selon lesquelles une femme sur trois sera victime dans tous les pays \u00e0 des violences au cours de sa vie, comme\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes - industriall-union","description":"La campagne se base sur les statistiques selon lesquelles une femme sur trois sera victime dans tous les pays \u00e0 des violences au cours de sa vie, comme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/","og_locale":"fr_FR","og_type":"article","og_title":"Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes","og_description":"La campagne se base sur les statistiques selon lesquelles une femme sur trois sera victime dans tous les pays \u00e0 des violences au cours de sa vie, comme","og_url":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/","og_site_name":"industriall-union","article_modified_time":"2025-02-08T14:52:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/","url":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/","name":"Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2013-02-18T14:47:31+00:00","dateModified":"2025-02-08T14:52:30+00:00","description":"La campagne se base sur les statistiques selon lesquelles une femme sur trois sera victime dans tous les pays \u00e0 des violences au cours de sa vie, comme","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-se-soulevent-pour-combattre-la-violence-contre-les-femmes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/fr\/article\/"},{"@type":"ListItem","position":3,"name":"Les syndicats se soul\u00e8vent pour combattre la violence contre les femmes"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/174523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=174523"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=174523"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=174523"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=174523"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=174523"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=174523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}