{"id":148200,"date":"2018-11-30T10:52:57","date_gmt":"2018-11-30T10:52:57","guid":{"rendered":"https:\/\/admin.industriall-union.org\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/"},"modified":"2025-02-03T23:41:52","modified_gmt":"2025-02-03T23:41:52","slug":"les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/","title":{"rendered":"Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance"},"content":{"rendered":"<p>En d\u00e9but d&rsquo;ann\u00e9e, 132 travailleurs ont \u00e9t\u00e9 renvoy\u00e9s pour avoir adh\u00e9r\u00e9s au syndicat Petrol-\u0130\u015f. N\u00e9anmoins, les travailleurs licenci\u00e9s se rendent au travail tous les matins o\u00f9 ils restent sur la ligne de piquetage jusqu&rsquo;\u00e0 la fin du deuxi\u00e8me quart de travail.<\/p><p>Des politiciens, des journalistes, des syndicalistes, des membres de la communaut\u00e9 et des artistes leur ont rendu visite sur leur lieu de gr\u00e8ve, et leur d\u00e9termination \u00e0 r\u00e9sister est forte. Les travailleurs passent le temps \u00e0 lire les livres qui leurs sont offerts et qui viennent alimenter une biblioth\u00e8que de r\u00e9sistance.<\/p><p>Une campagne mondiale a \u00e9t\u00e9 r\u00e9alis\u00e9e, y compris <a href=\"http:\/\/www.industriall-union.org\/fr\/les-travailleurs-et-travailleuses-dyves-rocher-licencies-sont-alles-plaider-leur-cause-a-geneve-et\">une visite au si\u00e8ge de la compagnie \u00e0 Paris<\/a>.<\/p><p>Le conflit a re\u00e7u une couverture m\u00e9diatique importante de la part de la t\u00e9l\u00e9vision et de la radio. En outre, en octobre, une d\u00e9l\u00e9gation de travailleurs a fait une d\u00e9claration au Parlement turc \u00e0 l&rsquo;invitation du Parti r\u00e9publicain du Peuple (CHP), qui fait partie de l&rsquo;opposition.<\/p><p>Le 23 octobre, une importante manifestation de solidarit\u00e9 a r\u00e9uni des centaines de personnes venues exprimer leur soutien.<\/p><p>L&rsquo;hiver arrive. Il fait froid sur la ligne de piquetage et les travailleurs ont besoin de chaleur et d&rsquo;un abri. Ils ont allum\u00e9 un feu dans un brasero et mont\u00e9 une tente pour s&rsquo;abriter de la pluie, du froid et de la neige, prochainement attendue. Mais le 19 novembre, le gouverneur de district a interdit le feu, la tente et l&rsquo;utilisation des m\u00e9gaphones. Par ailleurs, la zone de piquetage a fait l&rsquo;objet de contr\u00f4les par la police anti-\u00e9meute au cours des derni\u00e8res mois.<\/p><p>Le Secr\u00e9taire g\u00e9n\u00e9ral adjoint d&rsquo;IndustriALL Global Union, Kemal \u00d6zkan, a d\u00e9clar\u00e9:<\/p><p>&laquo;&nbsp;L&rsquo;esprit et la r\u00e9sistance de ces travailleurs est une source d&rsquo;inspiration pour chacun de nous. Ils n&rsquo;abandonnerons pas et nous continuerons de les soutenir.<\/p><p>&laquo;&nbsp;Yves Rocher, vous avez vu leur force et leur d\u00e9termination. Ils ne seront pas vaincus. Il est temps que vous les r\u00e9int\u00e9griez et reconnaissiez le syndicat&nbsp;&raquo;.<\/p><p>Plusieurs actions en soutien des travailleurs turcs sont en cours de pr\u00e9paration par l&rsquo;affili\u00e9 fran\u00e7ais \u00e0 IndustriALL, la FCE-CFDT.<\/p><p>Flormar est une marque de cosm\u00e9tiques turque, d\u00e9tenue majoritairement par Yves Rocher et dont le march\u00e9 primaire se trouve au Moyen-Orient et en Asie.<\/p><ul><li>Suivez la <a href=\"https:\/\/www.facebook.com\/flormardirenisi\/\">page Facebook<\/a> des travailleurs de Flormar et laissez leur un message de soutien<\/li><\/ul>","protected":false},"featured_media":0,"template":"","issues":[424],"companies":[149],"regions":[250],"sectors":[476],"article_tags":[],"class_list":["post-148200","article","type-article","status-publish","hentry","issues-violation","companies-yves-rocher","regions-turkiye","sectors-chemical-pharmaceutical-bio-science"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance - industriall-union<\/title>\n<meta name=\"description\" content=\"En d\u00e9but d&rsquo;ann\u00e9e, 132 travailleurs ont \u00e9t\u00e9 renvoy\u00e9s pour avoir adh\u00e9r\u00e9s au syndicat Petrol-\u0130\u015f. N\u00e9anmoins, les travailleurs licenci\u00e9s se rendent au\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance\" \/>\n<meta property=\"og:description\" content=\"En d\u00e9but d&rsquo;ann\u00e9e, 132 travailleurs ont \u00e9t\u00e9 renvoy\u00e9s pour avoir adh\u00e9r\u00e9s au syndicat Petrol-\u0130\u015f. N\u00e9anmoins, les travailleurs licenci\u00e9s se rendent au\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-03T23:41:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/\",\"name\":\"Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2018-11-30T10:52:57+00:00\",\"dateModified\":\"2025-02-03T23:41:52+00:00\",\"description\":\"En d\u00e9but d&rsquo;ann\u00e9e, 132 travailleurs ont \u00e9t\u00e9 renvoy\u00e9s pour avoir adh\u00e9r\u00e9s au syndicat Petrol-\u0130\u015f. N\u00e9anmoins, les travailleurs licenci\u00e9s se rendent au\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance - industriall-union","description":"En d\u00e9but d&rsquo;ann\u00e9e, 132 travailleurs ont \u00e9t\u00e9 renvoy\u00e9s pour avoir adh\u00e9r\u00e9s au syndicat Petrol-\u0130\u015f. N\u00e9anmoins, les travailleurs licenci\u00e9s se rendent au","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/","og_locale":"fr_FR","og_type":"article","og_title":"Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance","og_description":"En d\u00e9but d&rsquo;ann\u00e9e, 132 travailleurs ont \u00e9t\u00e9 renvoy\u00e9s pour avoir adh\u00e9r\u00e9s au syndicat Petrol-\u0130\u015f. N\u00e9anmoins, les travailleurs licenci\u00e9s se rendent au","og_url":"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/","og_site_name":"industriall-union","article_modified_time":"2025-02-03T23:41:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/","url":"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/","name":"Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2018-11-30T10:52:57+00:00","dateModified":"2025-02-03T23:41:52+00:00","description":"En d\u00e9but d&rsquo;ann\u00e9e, 132 travailleurs ont \u00e9t\u00e9 renvoy\u00e9s pour avoir adh\u00e9r\u00e9s au syndicat Petrol-\u0130\u015f. N\u00e9anmoins, les travailleurs licenci\u00e9s se rendent au","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/les-travailleurs-d-yves-rocher-maintiennent-leur-position-apres-200-jours-de-resistance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"Les travailleurs d\u2019Yves Rocher maintiennent leur position apr\u00e8s 200 jours de r\u00e9sistance"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/148200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=148200"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=148200"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=148200"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=148200"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=148200"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=148200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}