{"id":147864,"date":"2019-05-16T13:19:03","date_gmt":"2019-05-16T13:19:03","guid":{"rendered":"https:\/\/admin.industriall-union.org\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/"},"modified":"2025-02-03T17:56:55","modified_gmt":"2025-02-03T17:56:55","slug":"zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/","title":{"rendered":"Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre"},"content":{"rendered":"<p>Bien que Mopani ait pr\u00e9text\u00e9 du vieillissement des puits et du co\u00fbt \u00e9lev\u00e9 de leur entretien, les syndicats ont indiqu\u00e9 que les compagnies mini\u00e8res ne se souciaient pas de la s\u00e9curit\u00e9 de l&rsquo;emploi. L&rsquo;actuel dialogue mondial entre IndustriALL Global Union et la compagnie Glencore, cot\u00e9e \u00e0 la Bourse de Londres, vise \u00e0 am\u00e9liorer les relations du travail; et les fermetures des mines constituent un test de l&rsquo;engagement de Glencore. IndustriALL a appris la nouvelle avec inqui\u00e9tude et attend que l&rsquo;engagement de Glencore avec les syndicats soit transparent, notamment pour att\u00e9nuer l&rsquo;impact des fermetures sur les mineurs et les communaut\u00e9s.<\/p><p>Concernant Konkola Copper Mines (KCM), une filiale de la compagnie Vedanta Resources, \u00e9galement cot\u00e9e \u00e0 la Bourse de Londres, les syndicats affirment que l&rsquo;entreprise aurait meilleur temps de reprendre ses activit\u00e9s plut\u00f4t que de mettre en veilleuse des puits. &nbsp;Les op\u00e9rations mini\u00e8res dans les puits souterrains ou \u00e0 ciel ouvert \u00e0 Nchanga ont \u00e9t\u00e9 arr\u00eat\u00e9es en janvier, entra\u00eenant le licenciement de 905 travailleurs. Le secteur minier emploie plus de 65 000 travailleurs, dont 30 000 directement. Les 35 000 autres travailleurs sont embauch\u00e9s dans des conditions de travail pr\u00e9caires sur des contrats de courte dur\u00e9e, assortis de bas salaires et de faibles avantages, par l&rsquo;interm\u00e9diaire de sous-traitants qui agissent dans un irrespect insupportable des normes de sant\u00e9 et de s\u00e9curit\u00e9 entra\u00eenant des d\u00e9c\u00e8s et des blessures.<\/p><figure class=\"imageArticle imageMedium\"><img decoding=\"async\" alt=\"\" src=\"\/wp-content\/uploads\/images\/2019\/ZAMBIA\/photo-2019-05-10-15-07-18.jpg\" style=\"width: 600px;height: 450px\" \/><figcaption class=\"imageContent\">&nbsp;<\/figcaption><\/figure><p>Lors d&rsquo;une conf\u00e9rence de presse tenue le 10 mai en pr\u00e9sence de deux autres syndicats Zambiens, NUMAW et UMUZ, Joseph Chewe, pr\u00e9sident du syndicat des mineurs de Zambie, affili\u00e9 \u00e0 IndustriALL, a observ\u00e9:<\/p><blockquote><p>&laquo;&nbsp;Mopani Copper Mines devrait s&rsquo;assurer que les travailleurs concern\u00e9s soient affect\u00e9s \u00e0 d&rsquo;autres op\u00e9rations. Il est triste de constater qu&rsquo;il est aujourd&rsquo;hui risqu\u00e9 de travailler pour Mopani en raison de l&rsquo;incertitude et de l&rsquo;ins\u00e9curit\u00e9 de l&rsquo;emploi. L&rsquo;all\u00e9gation selon laquelle la mine investit dans l&rsquo;avenir est creuse puisqu&rsquo;elle le fait aux d\u00e9pens des travailleurs. Les travailleurs sont syst\u00e9matiquement vis\u00e9s par la direction dans les mesures de r\u00e9duction des co\u00fbts d\u00e8s qu&rsquo;un probl\u00e8me survient. Les syndicats demandent \u00e0 faire partie de l&rsquo;\u00e9quipe technique qui inspectera les puits afin de prot\u00e9ger les int\u00e9r\u00eats des travailleurs&nbsp;&raquo;.<\/p><\/blockquote><p>Glen Mpufane, directeur d&rsquo;IndustriALL pour le secteur de l&rsquo;extraction mini\u00e8re, a d\u00e9clar\u00e9 que les compagnies multinationales devraient appliquer des pratiques \u00e9quitables en mati\u00e8re de travail:<\/p><blockquote><p>&laquo;&nbsp;Le temps est r\u00e9volu o\u00f9 les compagnies se d\u00e9barrassent des mineurs ayant travaill\u00e9 d&rsquo;arrache-pied pendant de nombreuses ann\u00e9es, en creusant des gisements de min\u00e9raux pr\u00e9cieux, et les renvoient chez eux avec un salaire de mis\u00e8re, alors qu&rsquo;elles r\u00e9alisent des b\u00e9n\u00e9fices. Les compagnies mini\u00e8res doivent agir de mani\u00e8re responsable en affectant les travailleurs \u00e0 d&rsquo;autres puits ou en leur payant des indemnit\u00e9s de licenciement \u00e9quitables. Les travailleurs ne doivent pas se retrouver sans rien, dans la pauvret\u00e9, comme cela s&rsquo;est produit dans le pass\u00e9&nbsp;&raquo;.<\/p><\/blockquote><blockquote><\/blockquote>","protected":false},"featured_media":0,"template":"","issues":[],"companies":[60],"regions":[311,357],"sectors":[495,494],"article_tags":[],"class_list":["post-147864","article","type-article","status-publish","hentry","companies-glencore","regions-sub-saharan-africa","regions-zambia","sectors-mining","sectors-mining-and-dgojp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre - industriall-union<\/title>\n<meta name=\"description\" content=\"Bien que Mopani ait pr\u00e9text\u00e9 du vieillissement des puits et du co\u00fbt \u00e9lev\u00e9 de leur entretien, les syndicats ont indiqu\u00e9 que les compagnies mini\u00e8res ne se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre\" \/>\n<meta property=\"og:description\" content=\"Bien que Mopani ait pr\u00e9text\u00e9 du vieillissement des puits et du co\u00fbt \u00e9lev\u00e9 de leur entretien, les syndicats ont indiqu\u00e9 que les compagnies mini\u00e8res ne se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-03T17:56:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/\",\"name\":\"Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2019-05-16T13:19:03+00:00\",\"dateModified\":\"2025-02-03T17:56:55+00:00\",\"description\":\"Bien que Mopani ait pr\u00e9text\u00e9 du vieillissement des puits et du co\u00fbt \u00e9lev\u00e9 de leur entretien, les syndicats ont indiqu\u00e9 que les compagnies mini\u00e8res ne se\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre - industriall-union","description":"Bien que Mopani ait pr\u00e9text\u00e9 du vieillissement des puits et du co\u00fbt \u00e9lev\u00e9 de leur entretien, les syndicats ont indiqu\u00e9 que les compagnies mini\u00e8res ne se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/","og_locale":"fr_FR","og_type":"article","og_title":"Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre","og_description":"Bien que Mopani ait pr\u00e9text\u00e9 du vieillissement des puits et du co\u00fbt \u00e9lev\u00e9 de leur entretien, les syndicats ont indiqu\u00e9 que les compagnies mini\u00e8res ne se","og_url":"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/","og_site_name":"industriall-union","article_modified_time":"2025-02-03T17:56:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/","url":"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/","name":"Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2019-05-16T13:19:03+00:00","dateModified":"2025-02-03T17:56:55+00:00","description":"Bien que Mopani ait pr\u00e9text\u00e9 du vieillissement des puits et du co\u00fbt \u00e9lev\u00e9 de leur entretien, les syndicats ont indiqu\u00e9 que les compagnies mini\u00e8res ne se","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/zambie-la-perte-de-3-000-emplois-met-en-lumiere-les-conditions-de-travail-precaires-dans-les-mines-de-cuivre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"Zambie: la perte de 3 000 emplois met en lumi\u00e8re les conditions de travail pr\u00e9caires dans les mines de cuivre"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/147864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=147864"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=147864"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=147864"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=147864"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=147864"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=147864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}