{"id":147584,"date":"2019-08-09T08:31:54","date_gmt":"2019-08-09T08:31:54","guid":{"rendered":"https:\/\/admin.industriall-union.org\/rencontre-natalia-marynyuk\/"},"modified":"2025-02-03T14:57:23","modified_gmt":"2025-02-03T14:57:23","slug":"rencontre-natalia-marynyuk","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/","title":{"rendered":"RENCONTRE: Natalia Marynyuk"},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" alt=\"\" src=\"\/wp-content\/uploads\/images\/Global-Worker\/2019-1\/rencontre.png\" style=\"width: 300px;height: 297px\" \/><\/p><p><strong>Dites-nous comment vous vous \u00eates \u00e9lev\u00e9e dans les rangs syndicaux dans un milieu de travail domin\u00e9 par les hommes<\/strong><\/p><blockquote><p>&ldquo;Quand j&rsquo;ai commenc\u00e9 \u00e0 travailler, j&rsquo;ai rejoint le Syndicat des M\u00e9tallurgistes et Mineurs d&rsquo;Ukraine (PMGU), affili\u00e9 \u00e0 IndustriALL Global Union. En ao\u00fbt 2017, plus de 20 ans apr\u00e8s mes d\u00e9buts, j&rsquo;ai \u00e9t\u00e9 \u00e9lue \u00e0 la t\u00eate de la d\u00e9l\u00e9gation syndicale. Je suis devenue la premi\u00e8re, et jusqu&rsquo;ici la seule, femme \u00e9lue \u00e0 la pr\u00e9sidence de la section syndicale en 85 ans d&rsquo;existence.<\/p><p>&ldquo;M\u00eame si les femmes travailleuses repr\u00e9sentent un peu moins de 30% de la main d&rsquo;\u0153uvre de l&rsquo;entreprise, elles sont de loin plus actives dans le syndicat que leurs coll\u00e8gues masculins. Sur les 114 militants PMGU chez ArcelorMittal, pr\u00e8s de 60% sont des femmes.&rdquo;<\/p><\/blockquote><p>Kryvy\u00ef Rih \u00e9tait un important centre minier et m\u00e9tallurgique au temps de l&rsquo;Union Sovi\u00e9tique et Kryvorizhstal Steel Works exportait ses produits dans plus de 30 pays dans le monde.<\/p><p>Active sur l&rsquo;ensemble du cycle m\u00e9tallurgique, extraction du minerai, production de concentr\u00e9, d&rsquo;agglom\u00e9rats, de coke, de fonte, d&rsquo;acier et de produits lamin\u00e9s, et avec 57.000 travailleurs et travailleuses, l&rsquo;aci\u00e9rie repr\u00e9sentait une proposition all\u00e9chante pour les acheteurs lors de sa privatisation en 2004.<\/p><p>En 2005, l&rsquo;entreprise a \u00e9t\u00e9 vendue \u00e0 Mittal pour 4,81 milliards de dollars, d\u00e9passant de loin les 3 milliards pr\u00e9dits par les analystes. Lorsque Mittal a repris Arcelor en 2006, c&rsquo;est devenu ArcelorMittal Kryvy\u00ef Rih.<\/p><p><strong>Qu&rsquo;est ce que la privatisation a signifi\u00e9 pour vous et vos coll\u00e8gues ?<\/strong><\/p><blockquote><p>&ldquo;Lorsque le processus de privatisation a \u00e9t\u00e9 annonc\u00e9 en 2003, les travailleurs et les syndicats ont exprim\u00e9 leurs pr\u00e9occupations quant \u00e0 l&rsquo;avenir de l&rsquo;emploi. Il y a eu une s\u00e9rie de manifestations pour r\u00e9clamer que le gouvernement adopte une enveloppe sociale. Elle devait \u00eatre respect\u00e9e par le nouveau propri\u00e9taire apr\u00e8s la privatisation pour prot\u00e9ger les travailleurs et travailleuses.<\/p><p>&ldquo;En cons\u00e9quence de cela, Kryvorizhstal Steel Works a \u00e9t\u00e9 privatis\u00e9e avec un plan social obligatoire assorti de 19 conditions \u00e0 observer par le nouveau propri\u00e9taire. C&rsquo;\u00e9tait une premi\u00e8re en Ukraine. Cependant, toute l&rsquo;attention n\u00e9cessaire n&rsquo;a pas \u00e9t\u00e9 donn\u00e9e \u00e0 l&rsquo;ensemble des 19 points, et le syndicat a r\u00e9agi en organisant des actions de protestation et des meetings pour obliger l&rsquo;employeur \u00e0 honorer ses engagements, y compris ses promesses de hausses salariales.<\/p><p>&ldquo;Entre 2005 et 2018, ArcelorMittal a en fait diminu\u00e9 la main d&rsquo;\u0153uvre de plus de moiti\u00e9, passant de quelque 57.000 salari\u00e9s \u00e0 moins de 21.000. Les coupes ont \u00e9t\u00e9 essentiellement effectu\u00e9es par des d\u00e9parts volontaires, mais cela n&rsquo;a pas rendu les choses plus simples pour les restants. Pendant cette p\u00e9riode au cours de laquelle la main d&rsquo;\u0153uvre a \u00e9t\u00e9 r\u00e9duite de mani\u00e8re draconienne, la production de fonte, d&rsquo;acier et de lamin\u00e9s de l&rsquo;entreprise est rest\u00e9e plus ou moins identique, augmentant m\u00eame l\u00e9g\u00e8rement.<\/p><p>&ldquo;Ajoutez \u00e0 cela l&rsquo;augmentation de la charge de travail, un manque d&rsquo;investissement conduisant \u00e0 la d\u00e9t\u00e9rioration des b\u00e2timents et du mat\u00e9riel et vous pouvez y voir un d\u00e9clin \u00e9vident des conditions de travail.&rdquo;<\/p><\/blockquote><p><strong>Comment le syndicat a-t-il g\u00e9r\u00e9 l&rsquo;antisyndicalisme de la direction de l&rsquo;entreprise ?<\/strong><\/p><blockquote><p>&ldquo;Les conditions propos\u00e9es aux travailleurs et travailleuses ont commenc\u00e9 \u00e0 s\u00e9rieusement se d\u00e9t\u00e9riorer avec l&rsquo;arriv\u00e9e d&rsquo;un nouveau directeur des ressources humaines en 2017. Il y a eu d\u00e8s le d\u00e9but une claire hostilit\u00e9 envers les syndicats :&nbsp;<\/p><p>les termes de la convention collective n&rsquo;ont pas \u00e9t\u00e9 respect\u00e9s et les propositions syndicales \u00e9taient ignor\u00e9es.<\/p><p>&ldquo;La situation s&rsquo;est d\u00e9t\u00e9rior\u00e9e, il y avait de faux tracts syndicaux ainsi que des publications sur les m\u00e9dias sociaux et dans la presse locale pour diffamer le syndicat. Le DRH a m\u00eame d\u00e9velopp\u00e9 pour 2018 un programme sp\u00e9cial antisyndical appel\u00e9 &lsquo;Plan d&rsquo;action destin\u00e9 \u00e0 r\u00e9duire l&rsquo;influence du syndicat&rsquo;.<\/p><p>&ldquo;Les appels de la part du syndicat ont \u00e9t\u00e9 ignor\u00e9s par la direction. Alors que nous avions convoqu\u00e9 les travailleurs pour une assembl\u00e9e, le DRH a fait passer de fausses informations sur le lieu et l&rsquo;ordre du jour dans l&rsquo;espoir d&rsquo;emp\u00eacher les travailleurs d&rsquo;exprimer des revendications collectives. Mais syndicat et travailleurs sont parvenus \u00e0 tenir ce rassemblement. Ils ont \u00e9galement fait parvenir au PDG d&rsquo;ArcelorMittal Kryvy\u00ef Rih un appel sign\u00e9 par 12.000 personnes, pour revendiquer de plus hauts salaires, une meilleure s\u00e9curit\u00e9 et une am\u00e9lioration du dialogue social. Ne recevant aucune r\u00e9ponse, le syndicat a d\u00e9cid\u00e9 \u00e0 l&rsquo;issue d&rsquo;un vote d&rsquo;entamer un conflit collectif en avril 2018.<\/p><p>&ldquo;Le mois suivant, par le biais d&rsquo;une m\u00e9diation au cours d&rsquo;une r\u00e9union marathon de 26 heures, un accord a \u00e9t\u00e9 conclu entre la direction et les syndicats. Le PDG a augment\u00e9 l&rsquo;enveloppe destin\u00e9e aux salaires \u00e0 1,1 milliard de hryvnias (40 millions de dollars) et a aussi renvoy\u00e9 le DRH contestable qui avait failli \u00e0 \u00e9tablir un dialogue social en toute bonne foi avec les salari\u00e9s.<\/p><p>&ldquo;Il y a encore des probl\u00e8mes, mais au moins \u00e0 ce jour nous avons un dialogue social avec l&rsquo;entreprise.<\/p><p>&ldquo;Depuis juin 2017, il existe un accord avec l&rsquo;Union Europ\u00e9enne sur l&rsquo;absence de visa d&rsquo;entr\u00e9e, ce qui permet aux citoyens ukrainiens de se rendre plus facilement en Europe. \u00c0 la suite de cela, de nombreuses personnes ont quitt\u00e9 l&rsquo;Ukraine \u00e0 la recherche de meilleures conditions de travail et en cons\u00e9quence, pour la premi\u00e8re fois cette ann\u00e9e, l&rsquo;entreprise a eu des probl\u00e8mes \u00e0 trouver suffisamment de chauffeurs exp\u00e9riment\u00e9s.<\/p><p>&ldquo;Apr\u00e8s l&rsquo;effondrement d&rsquo;un toit en mars de l&rsquo;ann\u00e9e derni\u00e8re, entra\u00eenant la mort d&rsquo;un ouvrier, une \u00e9valuation des b\u00e2timents et des travaux de r\u00e9paration ont \u00e9t\u00e9 entrepris.<\/p><p>&ldquo;Ainsi, la question de meilleurs salaires et conditions d&rsquo;emploi reste cruciale pour l&rsquo;entreprise.&rdquo;<\/p><\/blockquote><figure class=\"imageArticle imageMedium\"><img decoding=\"async\" alt=\"\" src=\"\/wp-content\/uploads\/images\/Global-Worker\/2019-1\/img_1440.jpg\" style=\"width: 500px\" \/><figcaption class=\"imageContent\"><div class=\"imageCaption\"><p>Natalia Marynyuk. PMGU<\/p><\/div><\/figcaption><\/figure><p><strong>Quelle est l&rsquo;importance de la solidarit\u00e9 internationale pour votre syndicat ?<\/strong><\/p><blockquote><p>&ldquo;La reconnaissance de notre conflit et son soutien par le biais de la solidarit\u00e9 internationale ont \u00e9t\u00e9 importants pour d\u00e9boucher sur une solution. D\u00e9j\u00e0 en 2015, avec le soutien d&rsquo;IndustriALL, les syndicats d&rsquo;ArcelorMittal du Kazakhstan et d&rsquo;Ukraine avaient envoy\u00e9 une demande au PDG de l&rsquo;entreprise pour permettre \u00e0 leurs repr\u00e9sentants de faire partie du Comit\u00e9 d&rsquo;entreprise europ\u00e9en d&rsquo;ArcelorMittal.<\/p><p>&ldquo;Lors d&rsquo;une r\u00e9union \u00e0 Luxembourg en juillet 2018, les syndicats d&rsquo;ArcelorMittal ont constitu\u00e9 un r\u00e9seau mondial et se sont engag\u00e9s \u00e0 rechercher un dialogue social au plan mondial avec le plus gros producteur d&rsquo;acier au monde. Et les syndicats ukrainiens en faisaient partie.<\/p><p>&ldquo;Cette plateforme a permis au syndicat de soulever ses pr\u00e9occupations sur le dialogue social avec la haute direction mondiale d&rsquo;ArcelorMittal. Je fais maintenant partie du Conseil paritaire mondial d&rsquo;ArcelorMittal sur la sant\u00e9 et s\u00e9curit\u00e9, ce qui a \u00e9galement permis d&rsquo;am\u00e9liorer le dialogue social au plan local.&rdquo;<\/p><\/blockquote><section class=\"boxTurquoise\"><h2>PMGU&nbsp;<\/h2><p><strong>Le PMGU est pour l&rsquo;instant le plus important syndicat d&rsquo;ArcelorMittal Kryvy\u00ef Rih, repr\u00e9sentant plus de 70% des travailleurs et travailleuses. Environ 10% de la main d&rsquo;\u0153uvre n&rsquo;est pas syndiqu\u00e9e et les 20% restants sont repr\u00e9sent\u00e9s par 10 autres syndicats, dont l&rsquo;affili\u00e9 d&rsquo;IndustriALL, le Syndicat ind\u00e9pendant des mineurs d&rsquo;Ukraine.<\/strong><\/p><\/section>","protected":false},"featured_media":0,"template":"","issues":[408],"companies":[],"regions":[252],"sectors":[],"article_tags":[],"class_list":["post-147584","article","type-article","status-publish","hentry","issues-global-worker","regions-ukraine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>RENCONTRE: Natalia Marynyuk - industriall-union<\/title>\n<meta name=\"description\" content=\"Dites-nous comment vous vous \u00eates \u00e9lev\u00e9e dans les rangs syndicaux dans un milieu de travail domin\u00e9 par les hommes&ldquo;Quand j&rsquo;ai commenc\u00e9 \u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RENCONTRE: Natalia Marynyuk\" \/>\n<meta property=\"og:description\" content=\"Dites-nous comment vous vous \u00eates \u00e9lev\u00e9e dans les rangs syndicaux dans un milieu de travail domin\u00e9 par les hommes&ldquo;Quand j&rsquo;ai commenc\u00e9 \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-03T14:57:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/\",\"name\":\"RENCONTRE: Natalia Marynyuk - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2019-08-09T08:31:54+00:00\",\"dateModified\":\"2025-02-03T14:57:23+00:00\",\"description\":\"Dites-nous comment vous vous \u00eates \u00e9lev\u00e9e dans les rangs syndicaux dans un milieu de travail domin\u00e9 par les hommes&ldquo;Quand j&rsquo;ai commenc\u00e9 \u00e0\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"RENCONTRE: Natalia Marynyuk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RENCONTRE: Natalia Marynyuk - industriall-union","description":"Dites-nous comment vous vous \u00eates \u00e9lev\u00e9e dans les rangs syndicaux dans un milieu de travail domin\u00e9 par les hommes&ldquo;Quand j&rsquo;ai commenc\u00e9 \u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/","og_locale":"fr_FR","og_type":"article","og_title":"RENCONTRE: Natalia Marynyuk","og_description":"Dites-nous comment vous vous \u00eates \u00e9lev\u00e9e dans les rangs syndicaux dans un milieu de travail domin\u00e9 par les hommes&ldquo;Quand j&rsquo;ai commenc\u00e9 \u00e0","og_url":"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/","og_site_name":"industriall-union","article_modified_time":"2025-02-03T14:57:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/","url":"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/","name":"RENCONTRE: Natalia Marynyuk - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2019-08-09T08:31:54+00:00","dateModified":"2025-02-03T14:57:23+00:00","description":"Dites-nous comment vous vous \u00eates \u00e9lev\u00e9e dans les rangs syndicaux dans un milieu de travail domin\u00e9 par les hommes&ldquo;Quand j&rsquo;ai commenc\u00e9 \u00e0","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/rencontre-natalia-marynyuk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"RENCONTRE: Natalia Marynyuk"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/147584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=147584"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=147584"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=147584"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=147584"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=147584"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=147584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}