{"id":147558,"date":"2019-09-03T14:57:58","date_gmt":"2019-09-03T14:57:58","guid":{"rendered":"https:\/\/admin.industriall-union.org\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/"},"modified":"2025-02-03T14:33:38","modified_gmt":"2025-02-03T14:33:38","slug":"les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/","title":{"rendered":"Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages"},"content":{"rendered":"<p>Cette violence est une r\u00e9p\u00e9tition de ce qui s&rsquo;est d\u00e9j\u00e0 pass\u00e9 au cours d&rsquo;autres attaques x\u00e9nophobes dans le pays et la police a indiqu\u00e9 avoir proc\u00e9d\u00e9 \u00e0 diff\u00e9rentes arrestations.<\/p><p>Louise Modikwe de l&rsquo;affili\u00e9 d&rsquo;IndustriALL Global Union du textile, Southern African Clothing and Textile Union, qui est \u00e9galement la Secr\u00e9taire pour la province de Gauteng du Congr\u00e8s des syndicats sud-africains COSATU, a d\u00e9clar\u00e9&nbsp;:<\/p><blockquote><p>&ldquo;Le COSATU est choqu\u00e9 par la violence exerc\u00e9e \u00e0 l&rsquo;\u00e9gard de ressortissants \u00e9trangers, en particulier nig\u00e9rians, qui a d\u00e9but\u00e9 la semaine derni\u00e8re apr\u00e8s qu&rsquo;un chauffeur de taxi a \u00e9t\u00e9 tu\u00e9 \u00e0 Pretoria. Cette violence est aliment\u00e9e par les d\u00e9fis \u00e9conomiques pr\u00e9sents en Afrique du Sud et en Afrique en g\u00e9n\u00e9ral, qui sont le r\u00e9sultat des \u00e9checs des gouvernements \u00e0 \u00e9laborer des politiques \u00e9conomiques qui fassent cro\u00eetre les \u00e9conomies et cr\u00e9ent des emplois. Les interventions des gouvernements au niveau de la cr\u00e9ation d&rsquo;emploi, de la gestion des \u00e9trangers sans papiers et du contr\u00f4le des stup\u00e9fiants au sein des communaut\u00e9s sont souvent d\u00e9ficientes.&rdquo;<\/p><\/blockquote><p>La F\u00e9d\u00e9ration sud-africaine des syndicats (SAFTU) \u00e0 laquelle l&rsquo;affili\u00e9 d&rsquo;IndustriALL, le Syndicat national des m\u00e9tallurgistes d&rsquo;Afrique du Sud, est \u00e9galement affili\u00e9, a d\u00e9clar\u00e9&nbsp;:<\/p><blockquote><p>&ldquo;La SAFTU r\u00e9p\u00e8te que les migrants n&rsquo;ont rien \u00e0 voir avec le taux de ch\u00f4mage \u00e9lev\u00e9 de 38%. Ils n&rsquo;ont rien \u00e0 voir avec le fait que deux tiers des Sud-africains vivent dans la pauvret\u00e9. Les in\u00e9galit\u00e9s auxquelles les Sud-africains font face ne sont pas cr\u00e9\u00e9es par les migrants pauvres venus d&rsquo;Afrique et d&rsquo;Asie, mais \u00e9manent du syst\u00e8me capitaliste qui divise et exploite la classe ouvri\u00e8re noire.&rdquo;<\/p><\/blockquote><p>Les syndicats ont indiqu\u00e9 que la s\u00fbret\u00e9 et la s\u00e9curit\u00e9 \u00e9taient faibles en raison de l&rsquo;\u00e9chec de la Police sud-africaine \u00e0 faire son devoir en termes de maintien de l&rsquo;ordre et de l&rsquo;\u00e9tat de droit. Ils ajoutent que cela pourrait \u00eatre une des raisons pour lesquelles le crime est end\u00e9mique dans le pays.<\/p><p>Les syndicats ont \u00e9galement condamn\u00e9 les pratiques de certains employeurs qui pr\u00e9f\u00e8rent les sans papiers aux travailleurs et travailleuses sud-africains. Les sans papiers sont pay\u00e9s en dessous du salaire minimum de 3.500 rands (US $230). Ils affirment que cela cr\u00e9e des conflits entre travailleurs.<\/p><p>Avec une croissance molle de 2,8% par an en Afrique sub-saharienne, les emplois sont difficiles \u00e0 trouver et l&rsquo;Afrique du Sud est per\u00e7ue comme un pays offrant de meilleures perspectives que d&rsquo;autres. Des efforts sont actuellement entrepris pour cr\u00e9er des emplois sur le continent, parmi lesquels l&rsquo;Agenda 2063 de l&rsquo;Union africaine et la Zone de libre-\u00e9change continentale africaine, entre autres initiatives.<\/p><p><em>Photo:&nbsp;&copy; Ihsaan Haffejee, 2 septembre &#8211; <\/em>Des personnes fuient la police qui tente de disperser une foule qui tente de piller des entreprises appartenant \u00e0 des migrants<\/p>","protected":false},"featured_media":0,"template":"","issues":[],"companies":[],"regions":[350,311],"sectors":[],"article_tags":[],"class_list":["post-147558","article","type-article","status-publish","hentry","regions-south-africa","regions-sub-saharan-africa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages - industriall-union<\/title>\n<meta name=\"description\" content=\"Cette violence est une r\u00e9p\u00e9tition de ce qui s&rsquo;est d\u00e9j\u00e0 pass\u00e9 au cours d&rsquo;autres attaques x\u00e9nophobes dans le pays et la police a indiqu\u00e9 avoir\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages\" \/>\n<meta property=\"og:description\" content=\"Cette violence est une r\u00e9p\u00e9tition de ce qui s&rsquo;est d\u00e9j\u00e0 pass\u00e9 au cours d&rsquo;autres attaques x\u00e9nophobes dans le pays et la police a indiqu\u00e9 avoir\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-03T14:33:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/\",\"name\":\"Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2019-09-03T14:57:58+00:00\",\"dateModified\":\"2025-02-03T14:33:38+00:00\",\"description\":\"Cette violence est une r\u00e9p\u00e9tition de ce qui s&rsquo;est d\u00e9j\u00e0 pass\u00e9 au cours d&rsquo;autres attaques x\u00e9nophobes dans le pays et la police a indiqu\u00e9 avoir\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages - industriall-union","description":"Cette violence est une r\u00e9p\u00e9tition de ce qui s&rsquo;est d\u00e9j\u00e0 pass\u00e9 au cours d&rsquo;autres attaques x\u00e9nophobes dans le pays et la police a indiqu\u00e9 avoir","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/","og_locale":"fr_FR","og_type":"article","og_title":"Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages","og_description":"Cette violence est une r\u00e9p\u00e9tition de ce qui s&rsquo;est d\u00e9j\u00e0 pass\u00e9 au cours d&rsquo;autres attaques x\u00e9nophobes dans le pays et la police a indiqu\u00e9 avoir","og_url":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/","og_site_name":"industriall-union","article_modified_time":"2025-02-03T14:33:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/","url":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/","name":"Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2019-09-03T14:57:58+00:00","dateModified":"2025-02-03T14:33:38+00:00","description":"Cette violence est une r\u00e9p\u00e9tition de ce qui s&rsquo;est d\u00e9j\u00e0 pass\u00e9 au cours d&rsquo;autres attaques x\u00e9nophobes dans le pays et la police a indiqu\u00e9 avoir","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-sud-africains-choques-par-la-xenophobie-et-les-pillages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"Les syndicats sud-africains choqu\u00e9s par la x\u00e9nophobie et les pillages"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/147558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=147558"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=147558"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=147558"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=147558"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=147558"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=147558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}