{"id":144956,"date":"2021-02-26T12:50:10","date_gmt":"2021-02-26T12:50:10","guid":{"rendered":"https:\/\/admin.industriall-union.org\/repression-des-syndicats-par-les-militaires-au-myanmar\/"},"modified":"2025-01-28T22:47:06","modified_gmt":"2025-01-28T22:47:06","slug":"repression-des-syndicats-par-les-militaires-au-myanmar","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/","title":{"rendered":"R\u00e9pression des syndicats par les militaires au Myanmar"},"content":{"rendered":"<p>Au d\u00e9but de cette semaine, <a href=\"http:\/\/www.industriall-union.org\/nationwide-strike-for-democracy-in-myanmar\">des centaines de milliers de personnes ont particip\u00e9 \u00e0 des manifestations de masse pacifiques<\/a> dans tout le Myanmar. Alors que le mouvement pacifique de d\u00e9sob\u00e9issance civile continue de protester contre la prise de pouvoir par les militaires au Myanmar, les autorit\u00e9s r\u00e9priment les syndicats et leurs dirigeants.<\/p><p>La police a lanc\u00e9 des mandats d&rsquo;arr\u00eat \u00e0 l&rsquo;encontre de 20 dirigeants syndicaux, dont la plupart sont issus de la F\u00e9d\u00e9ration des travailleurs industriels du Myanmar (IWFM), y compris son vice-pr\u00e9sident, Soe Lay.<\/p><p>Selon les informations en provenance du syndicat, des policiers en civil tentent de retrouver les dirigeants syndicaux qui ont particip\u00e9 \u00e0 la gr\u00e8ve nationale de lundi.<\/p><p>Le Pr\u00e9sident de l&rsquo;IWFM, Khang Zar, a d\u00e9clar\u00e9 dans un communiqu\u00e9&nbsp;:<\/p><blockquote><p>&ldquo;L&rsquo;IWFM a travaill\u00e9 sans rel\u00e2che pour prot\u00e9ger les droits et am\u00e9liorer la vie des travailleurs et travailleuses de la confection ainsi que de leurs familles depuis que nous avons \u00e9t\u00e9 autoris\u00e9s \u00e0 revenir dans le pays apr\u00e8s la pr\u00e9c\u00e9dente dictature, en 2012.<\/p><p>Ensemble, le peuple du Myanmar et la communaut\u00e9 internationale peuvent ramener la d\u00e9mocratie. Par la d\u00e9sob\u00e9issance civile, les manifestations et les gr\u00e8ves, le peuple du Myanmar s&rsquo;exprime clairement. Nous avons besoin que la communaut\u00e9 internationale fasse de m\u00eame. Nous avons besoin que vous soyez \u00e0 nos c\u00f4t\u00e9s pour faire \u00e9chouer ce coup d&rsquo;\u00c9tat.&rdquo;<\/p><\/blockquote><p>\u00c0 ce jour, plus de 100 parlementaires \u00e9lus et titulaires des principaux minist\u00e8res, dont Aung San Suu Kyi, ont \u00e9t\u00e9 arr\u00eat\u00e9s par les militaires.<\/p><blockquote><p>&ldquo;Les syndicats jouent un r\u00f4le important dans la lutte pour le retour de la d\u00e9mocratie au Myanmar. Nous apportons notre soutien solidaire et sans \u00e9quivoque \u00e0 nos affili\u00e9s dans le pays et appelons au retour du gouvernement civil \u00e9lu par le peuple,&rdquo;<\/p><\/blockquote><p>a d\u00e9clar\u00e9 Valter Sanches, Secr\u00e9taire g\u00e9n\u00e9ral d&rsquo;IndustriALL.<\/p>","protected":false},"featured_media":0,"template":"","issues":[424,425],"companies":[],"regions":[177],"sectors":[],"article_tags":[],"class_list":["post-144956","article","type-article","status-publish","hentry","issues-violation","issues-workers-rights","regions-myanmar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>R\u00e9pression des syndicats par les militaires au Myanmar - industriall-union<\/title>\n<meta name=\"description\" content=\"Au d\u00e9but de cette semaine, des centaines de milliers de personnes ont particip\u00e9 \u00e0 des manifestations de masse pacifiques dans tout le Myanmar. Alors que\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9pression des syndicats par les militaires au Myanmar\" \/>\n<meta property=\"og:description\" content=\"Au d\u00e9but de cette semaine, des centaines de milliers de personnes ont particip\u00e9 \u00e0 des manifestations de masse pacifiques dans tout le Myanmar. Alors que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T22:47:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/\",\"name\":\"R\u00e9pression des syndicats par les militaires au Myanmar - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2021-02-26T12:50:10+00:00\",\"dateModified\":\"2025-01-28T22:47:06+00:00\",\"description\":\"Au d\u00e9but de cette semaine, des centaines de milliers de personnes ont particip\u00e9 \u00e0 des manifestations de masse pacifiques dans tout le Myanmar. Alors que\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e9pression des syndicats par les militaires au Myanmar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9pression des syndicats par les militaires au Myanmar - industriall-union","description":"Au d\u00e9but de cette semaine, des centaines de milliers de personnes ont particip\u00e9 \u00e0 des manifestations de masse pacifiques dans tout le Myanmar. Alors que","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9pression des syndicats par les militaires au Myanmar","og_description":"Au d\u00e9but de cette semaine, des centaines de milliers de personnes ont particip\u00e9 \u00e0 des manifestations de masse pacifiques dans tout le Myanmar. Alors que","og_url":"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/","og_site_name":"industriall-union","article_modified_time":"2025-01-28T22:47:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/","url":"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/","name":"R\u00e9pression des syndicats par les militaires au Myanmar - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2021-02-26T12:50:10+00:00","dateModified":"2025-01-28T22:47:06+00:00","description":"Au d\u00e9but de cette semaine, des centaines de milliers de personnes ont particip\u00e9 \u00e0 des manifestations de masse pacifiques dans tout le Myanmar. Alors que","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/repression-des-syndicats-par-les-militaires-au-myanmar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"R\u00e9pression des syndicats par les militaires au Myanmar"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/144956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=144956"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=144956"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=144956"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=144956"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=144956"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=144956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}