{"id":144717,"date":"2021-05-14T09:10:27","date_gmt":"2021-05-14T09:10:27","guid":{"rendered":"https:\/\/admin.industriall-union.org\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/"},"modified":"2025-01-28T17:05:25","modified_gmt":"2025-01-28T17:05:25","slug":"des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/","title":{"rendered":"Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd"},"content":{"rendered":"<p>Ce cong\u00e9 \u00e9tait traditionnellement allong\u00e9 pour les travailleurs de l&#039;habillement au Bangladesh, qui c\u00e9l\u00e9braient ce festival avec famille et amis. Le gouvernement avait annonc\u00e9 trois jours de cong\u00e9 pour cette ann\u00e9e, mais le Conseil d&#039;IndustriALL pour le Bangladesh, qui regroupe les affili\u00e9s de ce pays, avait pass\u00e9 un accord avec l&#039;association des propri\u00e9taires d&#039;usines, BGMEA, pour appeler ensemble les employeurs \u00e0 accorder un minimum de cinq \u00e0 dix jours.<\/p><p>Lorsque le groupe Ha-meem a annonc\u00e9 \u00e0 peine trois jours de cong\u00e9, une action de protestation spontan\u00e9e a \u00e9clat\u00e9 \u00e0 l&#039;usine Creative Collection, dans le district de Gazipur.<\/p><p>Des policiers venus en nombre ont repouss\u00e9 les manifestants avec des gaz lacrymog\u00e8nes et des balles en caoutchouc. 22 travailleurs au moins ont \u00e9t\u00e9 bless\u00e9s par ces balles, certains atteints de plus de 50 impacts. Ce n&#039;est qu&#039;apr\u00e8s l&#039;intervention violente de la police que l&#039;entreprise a allong\u00e9 le cong\u00e9 de l&#039;A\u00efd.<\/p><p>Saluddin Shapon, le pr\u00e9sident par int\u00e9rim du Conseil d&#039;IndustriALL pour le Bangladesh (BIC) a d\u00e9clar\u00e9 :<\/p><blockquote><p>&quot;Nous condamnons fermement les tirs de la police contre les manifestants. La question aurait d\u00fb \u00eatre r\u00e9gl\u00e9e par le dialogue social avec les travailleurs. La pr\u00e9sence d&#039;un syndicat dans l&#039;usine aurait pu pr\u00e9server la paix sociale et trouver une solution par la discussion.&quot;<\/p><\/blockquote><p>Depuis le confinement r\u00e9cemment impos\u00e9 au Bangladesh, les travailleurs rencontrent d&#039;\u00e9normes difficult\u00e9s. Les ateliers de confection peuvent continuer \u00e0 produire pendant le confinement et le personnel risque d&#039;\u00eatre contamin\u00e9 sur place et pendant les d\u00e9placements de et vers leur domicile. En l&#039;absence de transports publics, les travailleurs consacrent une part importante de leur r\u00e9mun\u00e9ration au transport qui ne laisse que tr\u00e8s peu pour les d\u00e9penses du m\u00e9nage.<\/p><blockquote><p>&quot;Nous sommes scandalis\u00e9s par les tactiques violentes et muscl\u00e9es que la police utilise contre les travailleurs. La violence de cette r\u00e9action va \u00e0 l&#039;encontre des normes internationales de respect des droits de l&#039;homme et des droits des travailleurs. Le respect des droits des travailleurs \u00e0 la libert\u00e9 syndicale et \u00e0 la n\u00e9gociation collective dans le groupe Ha-meem et au Bangladesh aidera largement \u00e0 \u00e9viter la r\u00e9p\u00e9tition de tels incidents \u00e0 l&#039;avenir,&quot;<\/p><\/blockquote><p>a d\u00e9clar\u00e9 Apoorva Kaiwar, la secr\u00e9taire r\u00e9gionale d&#039;IndustriALL pour l&#039;Asie du Sud.&nbsp;<\/p>","protected":false},"featured_media":0,"template":"","issues":[362,424,425],"companies":[],"regions":[159],"sectors":[464],"article_tags":[],"class_list":["post-144717","article","type-article","status-publish","hentry","issues-covid-19","issues-violation","issues-workers-rights","regions-bangladesh","sectors-textile-leather-garment-shoes-and-textile-services"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd - industriall-union<\/title>\n<meta name=\"description\" content=\"Ce cong\u00e9 \u00e9tait traditionnellement allong\u00e9 pour les travailleurs de l&#039;habillement au Bangladesh, qui c\u00e9l\u00e9braient ce festival avec famille et amis. Le\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd\" \/>\n<meta property=\"og:description\" content=\"Ce cong\u00e9 \u00e9tait traditionnellement allong\u00e9 pour les travailleurs de l&#039;habillement au Bangladesh, qui c\u00e9l\u00e9braient ce festival avec famille et amis. Le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T17:05:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/\",\"name\":\"Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2021-05-14T09:10:27+00:00\",\"dateModified\":\"2025-01-28T17:05:25+00:00\",\"description\":\"Ce cong\u00e9 \u00e9tait traditionnellement allong\u00e9 pour les travailleurs de l&#039;habillement au Bangladesh, qui c\u00e9l\u00e9braient ce festival avec famille et amis. Le\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd - industriall-union","description":"Ce cong\u00e9 \u00e9tait traditionnellement allong\u00e9 pour les travailleurs de l&#039;habillement au Bangladesh, qui c\u00e9l\u00e9braient ce festival avec famille et amis. Le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/","og_locale":"fr_FR","og_type":"article","og_title":"Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd","og_description":"Ce cong\u00e9 \u00e9tait traditionnellement allong\u00e9 pour les travailleurs de l&#039;habillement au Bangladesh, qui c\u00e9l\u00e9braient ce festival avec famille et amis. Le","og_url":"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/","og_site_name":"industriall-union","article_modified_time":"2025-01-28T17:05:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/","url":"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/","name":"Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2021-05-14T09:10:27+00:00","dateModified":"2025-01-28T17:05:25+00:00","description":"Ce cong\u00e9 \u00e9tait traditionnellement allong\u00e9 pour les travailleurs de l&#039;habillement au Bangladesh, qui c\u00e9l\u00e9braient ce festival avec famille et amis. Le","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/des-travailleurs-de-l-039-habillement-atteints-par-des-tirs-alors-qu-039-ils-reclamaient-un-allongement-du-conge-de-l-039-aid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/fr\/article\/"},{"@type":"ListItem","position":3,"name":"Des travailleurs de l&#039;habillement atteints par des tirs alors qu&#039;ils r\u00e9clamaient un allongement du cong\u00e9 de l&#039;A\u00efd"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/144717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=144717"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=144717"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=144717"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=144717"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=144717"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=144717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}