{"id":144051,"date":"2022-04-12T08:20:41","date_gmt":"2022-04-12T08:20:41","guid":{"rendered":"https:\/\/admin.industriall-union.org\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/"},"modified":"2025-01-28T03:35:31","modified_gmt":"2025-01-28T03:35:31","slug":"les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/","title":{"rendered":"Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie"},"content":{"rendered":"<p>La production \u00e9nerg\u00e9tique de l&#039;Arm\u00e9nie est \u00e0 40 pour cent verte, parce qu&#039;elle vient d&#039;une centrale nucl\u00e9aire qui n&#039;\u00e9met pas de CO2. 20 autres pour cent viennent de l&#039;hydro\u00e9lectricit\u00e9. Mais cette source est saisonni\u00e8re et l&#039;Arm\u00e9nie a un accord avec l&#039;Iran pour un \u00e9change r\u00e9ciproque d&#039;\u00e9nergie suivant la saison.<\/p><p>Les participants \u00e0 l&#039;atelier ont soulign\u00e9 que les syndicats doivent avoir leur place \u00e0 la table pour faire que les conditions de travail soient obligatoirement discut\u00e9es pour une Transition juste vers une \u00e9nergie renouvelable. Les dossiers d&#039;offres pour la construction d&#039;une nouvelle centrale solaire portent sur la s\u00e9curit\u00e9 de l&rsquo;environnement ainsi que sur des caract\u00e9ristiques techniques accessoires. Mais les questions sociales en sont absentes, qu&#039;il s&#039;agisse de salaires d\u00e9cents ou de sant\u00e9 et de s\u00e9curit\u00e9. Il faut que les syndicats fassent pression sur le gouvernement pour que des chapitres sociaux soient incorpor\u00e9s.<\/p><p>Par le biais de la Conf\u00e9d\u00e9ration des syndicats d&#039;Arm\u00e9nie et de la CSI, il faudrait aussi solliciter les institutions financi\u00e8res internationales qui accordent des pr\u00eats pour la r\u00e9alisation de programmes \u00e9nerg\u00e9tiques et d&#039;autres projets ayant des crit\u00e8res et des propositions similaires pour qu&#039;elles incluent un volet social convenu avec les organisations syndicales. Cela garantirait que ces projets ne se r\u00e9alisent pas en sacrifiant les salaires des travailleurs, privant ainsi l&#039;Arm\u00e9nie de la possibilit\u00e9 d&#039;atteindre un jour des niveaux de salaires d\u00e9cents.<\/p><p>Diana Junquera Curiel, la directrice d&#039;IndustriALL en charge de l&#039;\u00e9nergie, s&#039;est exprim\u00e9e \u00e0 propos d&#039;une nouvelle initiative commune du <a href=\"https:\/\/www.industriall-union.org\/launch-of-initiative-for-a-just-transition-in-the-energy-sector\">TUC, LO Norv\u00e8ge et IndustriALL pour une Transition juste<\/a> dans le secteur de l&#039;\u00e9nergie.<\/p><p>Sophia Sch\u00f6nborn, secr\u00e9taire du syndicat IG BCE, a parl\u00e9 de l&#039;exp\u00e9rience de l&#039;Allemagne s&#039;agissant de l&#039;abandon de l&#039;extraction charbonni\u00e8re et des mesures de soutien aux travailleurs entre la fin des ann\u00e9es 1950 jusqu&#039;\u00e0 la fermeture des derniers puits de mine en 2018. Un engagement budg\u00e9taire de 40 milliards &euro; est pr\u00e9vu au cours des vingt prochaines ann\u00e9es pour la cr\u00e9ation de nouvelles industries, de p\u00f4les de technologie et de recherche dans les districts miniers, d&#039;infrastructures modernes, d&#039;emplois, de programmes de formation aux nouveaux emplois et d&#039;un programme de d\u00e9part \u00e0 la retraite anticip\u00e9e afin d&#039;att\u00e9nuer les impacts n\u00e9gatifs sur les travailleurs, les r\u00e9gions et les communaut\u00e9s.<\/p><p>IndustriALL compte trois affili\u00e9s en Arm\u00e9nie, le Syndicat des travailleurs de l&#039;industrie d&#039;Arm\u00e9nie, le Syndicat de l&#039;\u00e9lectricit\u00e9 de la R\u00e9publique d&#039;Arm\u00e9nie et le Syndicat de branche des Organisations syndicales des mineurs et des travailleurs de la m\u00e9tallurgie et de la joaillerie de la R\u00e9publique d&#039;Arm\u00e9nie.<\/p>","protected":false},"featured_media":0,"template":"","issues":[393,425],"companies":[],"regions":[204],"sectors":[483],"article_tags":[],"class_list":["post-144051","article","type-article","status-publish","hentry","issues-climate-change-just-transition","issues-workers-rights","regions-armenia","sectors-energy-oil-gas-electricity-and-nuclear"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie - industriall-union<\/title>\n<meta name=\"description\" content=\"La production \u00e9nerg\u00e9tique de l&#039;Arm\u00e9nie est \u00e0 40 pour cent verte, parce qu&#039;elle vient d&#039;une centrale nucl\u00e9aire qui n&#039;\u00e9met pas de CO2.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie\" \/>\n<meta property=\"og:description\" content=\"La production \u00e9nerg\u00e9tique de l&#039;Arm\u00e9nie est \u00e0 40 pour cent verte, parce qu&#039;elle vient d&#039;une centrale nucl\u00e9aire qui n&#039;\u00e9met pas de CO2.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T03:35:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/\",\"name\":\"Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2022-04-12T08:20:41+00:00\",\"dateModified\":\"2025-01-28T03:35:31+00:00\",\"description\":\"La production \u00e9nerg\u00e9tique de l&#039;Arm\u00e9nie est \u00e0 40 pour cent verte, parce qu&#039;elle vient d&#039;une centrale nucl\u00e9aire qui n&#039;\u00e9met pas de CO2.\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie - industriall-union","description":"La production \u00e9nerg\u00e9tique de l&#039;Arm\u00e9nie est \u00e0 40 pour cent verte, parce qu&#039;elle vient d&#039;une centrale nucl\u00e9aire qui n&#039;\u00e9met pas de CO2.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/","og_locale":"fr_FR","og_type":"article","og_title":"Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie","og_description":"La production \u00e9nerg\u00e9tique de l&#039;Arm\u00e9nie est \u00e0 40 pour cent verte, parce qu&#039;elle vient d&#039;une centrale nucl\u00e9aire qui n&#039;\u00e9met pas de CO2.","og_url":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/","og_site_name":"industriall-union","article_modified_time":"2025-01-28T03:35:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/","url":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/","name":"Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2022-04-12T08:20:41+00:00","dateModified":"2025-01-28T03:35:31+00:00","description":"La production \u00e9nerg\u00e9tique de l&#039;Arm\u00e9nie est \u00e0 40 pour cent verte, parce qu&#039;elle vient d&#039;une centrale nucl\u00e9aire qui n&#039;\u00e9met pas de CO2.","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/les-syndicats-d-039-armenie-discutent-d-039-une-transition-juste-dans-le-secteur-de-l-039-energie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"Les syndicats d&#039;Arm\u00e9nie discutent d&#039;une Transition juste dans le secteur de l&#039;\u00e9nergie"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/144051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=144051"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=144051"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=144051"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=144051"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=144051"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=144051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}