{"id":143448,"date":"2022-12-15T09:07:54","date_gmt":"2022-12-15T09:07:54","guid":{"rendered":"https:\/\/admin.industriall-union.org\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/"},"modified":"2025-01-27T23:04:43","modified_gmt":"2025-01-27T23:04:43","slug":"nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/","title":{"rendered":"Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz"},"content":{"rendered":"<p>C&rsquo;est tard dans la journ\u00e9e du vendredi 2 d\u00e9cembre, au terme d&rsquo;une r\u00e9union technique d&rsquo;une semaine tenue au si\u00e8ge de l&rsquo;OIT \u00e0 Gen\u00e8ve, que les n\u00e9gociations entre les repr\u00e9sentants des travailleurs, des gouvernements et des employeurs ont abouti \u00e0&nbsp;<a href=\"https:\/\/www.ilo.org\/wcmsp5\/groups\/public\/---ed_dialogue\/---sector\/documents\/meetingdocument\/wcms_863414.pdf\">un accord<\/a>&nbsp;sur l&rsquo;avenir du travail dans le secteur du p\u00e9trole et du gaz.<\/p><p>Les r\u00e9unions de ce type fournissent des orientations sur la mani\u00e8re d&rsquo;aborder et de traiter des enjeux propres \u00e0 un secteur. Elles rev\u00eatent une importance toute particuli\u00e8re lorsque de nouveaux secteurs voient le jour ou lorsque les secteurs existants se trouvent confront\u00e9s \u00e0 des changements majeurs r\u00e9sultant de la double transition climatique et technologique. En tant que contributeurs majeurs aux \u00e9missions de gaz \u00e0 effet de serre, les secteurs du p\u00e9trole et du gaz seront tr\u00e8s fortement impact\u00e9s par le besoin de d\u00e9carbonation. Pour les syndicats, il est primordial que ce processus se d\u00e9roule de mani\u00e8re planifi\u00e9e et structur\u00e9e, afin que de nouveaux emplois puissent \u00eatre cr\u00e9\u00e9s avant que les emplois existants ne disparaissent.<\/p><p>La d\u00e9l\u00e9gation syndicale \u00e9tait compos\u00e9e d&rsquo;experts du secteur p\u00e9trolier et gazier, \u00e9lus d\u00e9mocratiquement pour repr\u00e9senter les syndicats des \u00c9tats-Unis, du Br\u00e9sil, de Colombie, du Nigeria, d&rsquo;Irak, de Norv\u00e8ge, d&rsquo;Australie et d&rsquo;Indon\u00e9sie.&nbsp;Ils \u00e9taient soutenus par la CSI, IndustriALL Global Union et industriAll European Union.&nbsp;<\/p><p>Le Bureau international du travail a \u00e9labor\u00e9 un&nbsp;<a href=\"https:\/\/www.ilo.org\/wcmsp5\/groups\/public\/---ed_dialogue\/---sector\/documents\/publication\/wcms_859846.pdf\">rapport<\/a>&nbsp;qui a servi de base \u00e0 la discussion. Au d\u00e9but de la semaine, des questions sur les d\u00e9fis, les opportunit\u00e9s, les bonnes pratiques et les exigences ont \u00e9t\u00e9 soulev\u00e9es. Les n\u00e9gociateurs ont pr\u00e9sent\u00e9 leurs points de vue et leurs principales demandes. \u00c0 partir de ces contributions, le Bureau a r\u00e9dig\u00e9 un avant-projet de texte, dont les parties ont n\u00e9goci\u00e9 les amendements au cours de la semaine.<\/p><p>Pour les repr\u00e9sentants des travailleurs, les principales revendications \u00e9taient les suivantes&nbsp;:<\/p><ul><li>De futurs emplois syndiqu\u00e9s et d\u00e9cents, n\u00e9goci\u00e9s par le biais du dialogue social, avec la participation des syndicats au processus de d\u00e9cision.&nbsp;<\/li><li>Des r\u00e9f\u00e9rences au niveau \u00e9lev\u00e9 de sous-traitance dans l&rsquo;industrie, aux responsabilit\u00e9s des gouvernements lors de la mise en place de plans \u00e9nerg\u00e9tiques, et aux employeurs en ce qui concerne le devoir de diligence raisonnable dans la cha\u00eene d&rsquo;approvisionnement.<\/li><li>Un m\u00e9canisme de financement pour une transition juste dans le secteur.<\/li><li>L&rsquo;investissement dans les plans \u00e9nerg\u00e9tiques \u00e0 moyen et long terme, y compris la formation et le recyclage.&nbsp;<\/li><\/ul><p>La d\u00e9l\u00e9gation syndicale \u00e9tait insatisfaite \u00e0 la fois du d\u00e9roulement de la r\u00e9union et de ses r\u00e9sultats. Une occasion d&rsquo;aborder de nombreuses questions urgentes a \u00e9t\u00e9 manqu\u00e9e, notamment le probl\u00e8me des travailleurs externalis\u00e9s. Ceci \u00e9tait d\u00fb \u00e0 un manque d&rsquo;engagement de la part des employeurs. Aucune des grandes entreprises du secteur n&rsquo;a particip\u00e9 \u00e0 la r\u00e9union, et le n\u00e9gociateur en chef repr\u00e9sentant les employeurs, issu de l&rsquo;Organisation internationale des employeurs (OIE), n&rsquo;avait aucune exp\u00e9rience sp\u00e9cifique du secteur, dans la mesure o\u00f9 l&rsquo;OIE n\u00e9gocie des accords dans les secteurs du tourisme, de l&rsquo;\u00e9ducation, de l&rsquo;agriculture, des transports et de l&rsquo;\u00e9nergie, entre autres.&nbsp;<\/p><p>\u00c9tant donn\u00e9 que les conclusions n&rsquo;\u00e9taient pas aussi normatives que les syndicats l&rsquo;avaient esp\u00e9r\u00e9, la possibilit\u00e9 d&rsquo;\u00e9laborer un guide sectoriel sur la transition juste sera examin\u00e9e apr\u00e8s la r\u00e9union du Conseil d&rsquo;administration de l&rsquo;OIT l&rsquo;\u00e9t\u00e9 prochain.&nbsp;<\/p><p><img decoding=\"async\" alt=\"\" src=\"\" style=\"width: 600px;height: 338px\" \/><\/p><p>Diana Junquera Curiel, directrice d&rsquo;IndustriALL pour l&rsquo;\u00e9nergie et la transition juste, a d\u00e9clar\u00e9&nbsp;:<\/p><blockquote><p>&laquo;&nbsp;Lorsqu&rsquo;il s&rsquo;agit de transition juste dans ce secteur, les pr\u00e9occupations des travailleurs portent notamment sur le financement de la transition, la protection sociale et la qualit\u00e9 et le nombre d&rsquo;emplois d\u00e9cents qui seront disponibles.&nbsp;Si la transition ne s&rsquo;op\u00e8re pas dans le cadre du dialogue social, de la protection sociale, de la n\u00e9gociation collective et de l&rsquo;int\u00e9gration, l&rsquo;avenir sera insoutenable pour tous.&nbsp;&raquo;<\/p><\/blockquote><p>Dans sa d\u00e9claration finale, le pr\u00e9sident du groupe des travailleurs, Mike Smith, de l&rsquo;USW, a affirm\u00e9&nbsp;:<\/p><blockquote><p>&nbsp;&laquo;&nbsp;Nous nous r\u00e9jouissons d&rsquo;\u00eatre parvenus \u00e0 un accord sur ce document au terme d&rsquo;une semaine d&rsquo;intenses n\u00e9gociations.&nbsp;Nous sommes confiants que les conclusions constitueront une \u00e9tape sur le long chemin d&rsquo;une transition juste dans l&rsquo;industrie du p\u00e9trole et du gaz, avec le maintien d&rsquo;une industrie saine et productive qui facilite la cr\u00e9ation d&rsquo;emplois d\u00e9cents, de mani\u00e8re \u00e0 remplacer les emplois perdus par des emplois de valeur \u00e9quivalente ou sup\u00e9rieure.<\/p><\/blockquote><p>&laquo;&nbsp;Nous regrettons que ce document ne contienne aucune r\u00e9f\u00e9rence aux travailleurs externalis\u00e9s.&nbsp;Nous sommes particuli\u00e8rement pr\u00e9occup\u00e9s par le fait que l&rsquo;externalisation est tr\u00e8s r\u00e9pandue dans le secteur p\u00e9trolier et gazier, que cette pratique nuit aux conditions de travail et que les travailleurs externalis\u00e9s ne disposent pas d&rsquo;une voie de recours institutionnelle pour faire entendre leurs griefs.&nbsp;<\/p><blockquote><p>&laquo;&nbsp;Nous continuerons \u00e0 \u0153uvrer pour que toutes les personnes travaillant dans l&rsquo;industrie p\u00e9troli\u00e8re et gazi\u00e8re, qu&rsquo;il s&rsquo;agisse de travailleurs directs ou externalis\u00e9s, jouissent de la libert\u00e9 syndicale, de la sant\u00e9 et de la s\u00e9curit\u00e9 au travail, et de bonnes conditions de travail obtenues par le biais de conventions collectives.&nbsp;&raquo;<\/p><\/blockquote><p style=\"margin:0cm;text-align:start\"><span style=\"font-size:medium\"><span style=\"font-family:Calibri, sans-serif\"><span><span style=\"color:#000000\"><span style=\"font-style:normal\"><span><span style=\"font-weight:normal\"><span style=\"letter-spacing:normal\"><span><span style=\"text-transform:none\"><span><span><span><span><span style=\"text-decoration:none\">&nbsp;<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>","protected":false},"featured_media":0,"template":"","issues":[390,423],"companies":[],"regions":[],"sectors":[483],"article_tags":[],"class_list":["post-143448","article","type-article","status-publish","hentry","issues-future-of-work","issues-ilo-watch","sectors-energy-oil-gas-electricity-and-nuclear"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz - industriall-union<\/title>\n<meta name=\"description\" content=\"C&rsquo;est tard dans la journ\u00e9e du vendredi 2 d\u00e9cembre, au terme d&rsquo;une r\u00e9union technique d&rsquo;une semaine tenue au si\u00e8ge de l&rsquo;OIT \u00e0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz\" \/>\n<meta property=\"og:description\" content=\"C&rsquo;est tard dans la journ\u00e9e du vendredi 2 d\u00e9cembre, au terme d&rsquo;une r\u00e9union technique d&rsquo;une semaine tenue au si\u00e8ge de l&rsquo;OIT \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T23:04:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/\",\"name\":\"Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2022-12-15T09:07:54+00:00\",\"dateModified\":\"2025-01-27T23:04:43+00:00\",\"description\":\"C&rsquo;est tard dans la journ\u00e9e du vendredi 2 d\u00e9cembre, au terme d&rsquo;une r\u00e9union technique d&rsquo;une semaine tenue au si\u00e8ge de l&rsquo;OIT \u00e0\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz - industriall-union","description":"C&rsquo;est tard dans la journ\u00e9e du vendredi 2 d\u00e9cembre, au terme d&rsquo;une r\u00e9union technique d&rsquo;une semaine tenue au si\u00e8ge de l&rsquo;OIT \u00e0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz","og_description":"C&rsquo;est tard dans la journ\u00e9e du vendredi 2 d\u00e9cembre, au terme d&rsquo;une r\u00e9union technique d&rsquo;une semaine tenue au si\u00e8ge de l&rsquo;OIT \u00e0","og_url":"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/","og_site_name":"industriall-union","article_modified_time":"2025-01-27T23:04:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/","url":"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/","name":"Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2022-12-15T09:07:54+00:00","dateModified":"2025-01-27T23:04:43+00:00","description":"C&rsquo;est tard dans la journ\u00e9e du vendredi 2 d\u00e9cembre, au terme d&rsquo;une r\u00e9union technique d&rsquo;une semaine tenue au si\u00e8ge de l&rsquo;OIT \u00e0","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/nouvel-accord-de-l-oit-sur-l-avenir-du-travail-dans-le-secteur-du-petrole-et-du-gaz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"Nouvel accord de l\u2019OIT sur l\u2019avenir du travail dans le secteur du p\u00e9trole et du gaz"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/143448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=143448"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=143448"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=143448"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=143448"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=143448"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=143448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}