{"id":142985,"date":"2023-10-16T08:48:10","date_gmt":"2023-10-16T08:48:10","guid":{"rendered":"https:\/\/admin.industriall-union.org\/renforcer-le-reseau-coats\/"},"modified":"2025-01-27T18:43:59","modified_gmt":"2025-01-27T18:43:59","slug":"renforcer-le-reseau-coats","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/","title":{"rendered":"Renforcer le r\u00e9seau Coats"},"content":{"rendered":"<p>Au cours des deux jours de r\u00e9union, les participants ont partag\u00e9 leurs exp\u00e9riences en mati\u00e8re de n\u00e9gociation collective, d&rsquo;am\u00e9lioration des clauses des conventions et de d\u00e9fis \u00e0 relever.<\/p><p>Le Secr\u00e9taire g\u00e9n\u00e9ral d&rsquo;IndustriALL, Atle H\u00f8ie, s&rsquo;est adress\u00e9 aux participants et a soulign\u00e9 la n\u00e9cessit\u00e9 d&rsquo;\u00e9tablir des relations constructives avec les entreprises multinationales et l&rsquo;importance de cr\u00e9er des politiques communes ainsi qu&rsquo;une solidarit\u00e9 entre les syndicats.<\/p><p>Les membres ont \u00e9galement discut\u00e9 de l&rsquo;importance des r\u00e9seaux syndicaux dans le renforcement de leur pouvoir au sein de la cha\u00eene d&rsquo;approvisionnement, en soulignant que Coats, une grande entreprise multinationale, poss\u00e8de des installations dans plus de 50 pays et a r\u00e9cemment achet\u00e9 Rhenoflex et Texon. Le r\u00f4le des membres de l&rsquo;atelier a \u00e9t\u00e9 soulign\u00e9, ainsi que l&rsquo;importance de leur faire prendre conscience qu&rsquo;ils font partie d&rsquo;un r\u00e9seau plus large dans le cadre du pouvoir des travailleurs au sein de la cha\u00eene d&rsquo;approvisionnement.<\/p><p>Le site web du r\u00e9seau est un outil pr\u00e9cieux pour renforcer les liens transfrontaliers entre les membres des syndicats de Coats.<\/p><p>Le d\u00e9partement des ressources humaines de Coats \u00e0 l&rsquo;\u00e9chelle mondiale a pr\u00e9sent\u00e9 les initiatives de l&rsquo;entreprise visant \u00e0 accro\u00eetre la diversit\u00e9, en particulier en mati\u00e8re de genre, et \u00e0 cr\u00e9er une culture d&rsquo;appartenance. La r\u00e9union a \u00e9galement mis l&rsquo;accent sur la n\u00e9cessit\u00e9 de syndiquer toutes les usines Coats dans le monde, d&rsquo;y am\u00e9liorer la libert\u00e9 syndicale et de renforcer les n\u00e9gociations collectives.<\/p><p>En outre, des plans ont \u00e9t\u00e9 formul\u00e9s en vue de formaliser le r\u00e9seau en proposant les nominations de deux copr\u00e9sidents. Le r\u00e9seau a discut\u00e9 de la n\u00e9cessit\u00e9 de progresser vers un accord-cadre mondial avec l&rsquo;entreprise et un groupe de travail a commenc\u00e9 \u00e0 \u0153uvrer sur un projet d&rsquo;accord qui devrait \u00eatre finalis\u00e9 d&rsquo;ici la fin de l&rsquo;ann\u00e9e 2023.<\/p><p>Christina Hajagos-Clausen, Directrice de la section textile et habillement d&rsquo;IndustriALL, a d\u00e9clar\u00e9&nbsp;:<\/p><blockquote><p>&ldquo;IndustriALL met en place des r\u00e9seaux syndicaux pour relier tous les syndicats d&rsquo;une m\u00eame entreprise multinationale afin d&rsquo;accro\u00eetre l&rsquo;\u00e9change d&rsquo;informations, d&rsquo;am\u00e9liorer la communication entre les syndicats de diff\u00e9rents sites et pays et d&rsquo;accro\u00eetre la pr\u00e9sence syndicale au sein de l&rsquo;entreprise.<\/p><p>Cette rencontre, la quatri\u00e8me r\u00e9union annuelle du r\u00e9seau Coats, d\u00e9montre que le militantisme syndical transfrontalier et le dialogue social sont continuellement renforc\u00e9s tout au long de la cha\u00eene d&rsquo;approvisionnement de Coats&rdquo;.<\/p><\/blockquote><p>Cette r\u00e9union a \u00e9t\u00e9 organis\u00e9e par le syndicat marocain UMT, qui a r\u00e9cemment syndiqu\u00e9 l&rsquo;usine Coats de Casablanca.<\/p><p>Al-Arabi Hamouk,&nbsp; Secr\u00e9taire g\u00e9n\u00e9ral du SNTTC-UMT, a d\u00e9clar\u00e9 :<\/p><blockquote><p>&ldquo;Au cours de notre campagne de syndicalisation, soutenue par IndustriALL, nous avons recrut\u00e9 au sein de Coats au Maroc. Les travailleurs et travailleuses de l&rsquo;entreprise ont encore des revendications l\u00e9gitimes en suspens qui sont discut\u00e9es avec la direction locale. Notre appartenance au r\u00e9seau mondial Coats est cruciale pour nos efforts visant \u00e0 am\u00e9liorer les conditions de travail sur le site marocain, ainsi que pour \u00e9tablir un dialogue social mondial efficace avec l&rsquo;entreprise.&rdquo;<\/p><\/blockquote><p><br \/><\/p>","protected":false},"featured_media":0,"template":"","issues":[396,425],"companies":[],"regions":[300],"sectors":[464],"article_tags":[],"class_list":["post-142985","article","type-article","status-publish","hentry","issues-building-strong-unions","issues-workers-rights","regions-morocco","sectors-textile-leather-garment-shoes-and-textile-services"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Renforcer le r\u00e9seau Coats - industriall-union<\/title>\n<meta name=\"description\" content=\"Au cours des deux jours de r\u00e9union, les participants ont partag\u00e9 leurs exp\u00e9riences en mati\u00e8re de n\u00e9gociation collective, d&rsquo;am\u00e9lioration des clauses\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renforcer le r\u00e9seau Coats\" \/>\n<meta property=\"og:description\" content=\"Au cours des deux jours de r\u00e9union, les participants ont partag\u00e9 leurs exp\u00e9riences en mati\u00e8re de n\u00e9gociation collective, d&rsquo;am\u00e9lioration des clauses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T18:43:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/\",\"name\":\"Renforcer le r\u00e9seau Coats - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/#website\"},\"datePublished\":\"2023-10-16T08:48:10+00:00\",\"dateModified\":\"2025-01-27T18:43:59+00:00\",\"description\":\"Au cours des deux jours de r\u00e9union, les participants ont partag\u00e9 leurs exp\u00e9riences en mati\u00e8re de n\u00e9gociation collective, d&rsquo;am\u00e9lioration des clauses\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/ru\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Renforcer le r\u00e9seau Coats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Renforcer le r\u00e9seau Coats - industriall-union","description":"Au cours des deux jours de r\u00e9union, les participants ont partag\u00e9 leurs exp\u00e9riences en mati\u00e8re de n\u00e9gociation collective, d&rsquo;am\u00e9lioration des clauses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/","og_locale":"fr_FR","og_type":"article","og_title":"Renforcer le r\u00e9seau Coats","og_description":"Au cours des deux jours de r\u00e9union, les participants ont partag\u00e9 leurs exp\u00e9riences en mati\u00e8re de n\u00e9gociation collective, d&rsquo;am\u00e9lioration des clauses","og_url":"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/","og_site_name":"industriall-union","article_modified_time":"2025-01-27T18:43:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/","url":"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/","name":"Renforcer le r\u00e9seau Coats - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/#website"},"datePublished":"2023-10-16T08:48:10+00:00","dateModified":"2025-01-27T18:43:59+00:00","description":"Au cours des deux jours de r\u00e9union, les participants ont partag\u00e9 leurs exp\u00e9riences en mati\u00e8re de n\u00e9gociation collective, d&rsquo;am\u00e9lioration des clauses","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/fr\/renforcer-le-reseau-coats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/ru\/article\/"},{"@type":"ListItem","position":3,"name":"Renforcer le r\u00e9seau Coats"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/#website","url":"https:\/\/admin.industriall-union.org\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article\/142985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/media?parent=142985"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/issues?post=142985"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/companies?post=142985"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/regions?post=142985"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/sectors?post=142985"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/fr\/wp-json\/wp\/v2\/article_tags?post=142985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}