{"id":175276,"date":"2012-05-25T15:58:53","date_gmt":"2012-05-25T15:58:53","guid":{"rendered":"https:\/\/admin.industriall-union.org\/vallourec-2\/"},"modified":"2025-02-08T18:46:10","modified_gmt":"2025-02-08T18:46:10","slug":"vallourec-2","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/","title":{"rendered":"Vallourec"},"content":{"rendered":"<p>En el acuerdo se declara:<\/p><ul><li>En todas partes donde est\u00e1 establecido el Grupo, Vallourec aplica los convenios internacionales y las leyes nacionales y respeta las costumbres nacionales y las costumbres locales.<\/li><li>Como compa\u00f1\u00eda de categor\u00eda internacional, Vallourec se compromete en particular a respetar los derechos humanos y los principios fundamentales universales que protegen la dignidad, el respeto y la libertad de los empleados.<\/li><\/ul><p>En un anexo al acuerdo se especifican los principales convenios de la Organizaci\u00f3n Internacional del Trabajo abarcados por el acuerdo. Los convenios comprenden esferas como el derecho de libertad sindical y de negociaci\u00f3n colectiva, la exclusi\u00f3n de trabajo forzoso, la exclusi\u00f3n de trabajo infantil y el derecho a igualdad de remuneraci\u00f3n y no discriminaci\u00f3n.<\/p><p>El acuerdo, en el que se declara tambi\u00e9n que &quot;Vallourec pide a sus proveedores y subcontratistas que respeten esos derechos fundamentales, incorpora estos criterios en sus evaluaciones.<\/p><p>Para vigilar el acuerdo, se conviene en que la Direcci\u00f3n General informar\u00e1 anualmente al Comit\u00e9 de Trabajadores Europeos de las quejas recibidas durante el a\u00f1o y de las correspondientes medidas adoptadas.<\/p><p>El Grupo Vallourec suministra tubos a los sectores del petr\u00f3leo y el gas, generaci\u00f3n de energ\u00eda, ingenier\u00eda mec\u00e1nica, petroqu\u00edmica, autom\u00f3vil y arquitectura en acero. Con su sede central en Francia, Vallourec emplea a 18.000 personas, y tiene plantas en Asia, Europa, Am\u00e9rica del Norte y Am\u00e9rica Latina.<\/p>","protected":false},"featured_media":0,"template":"","issues":[407],"companies":[144],"regions":[],"sectors":[482,481,477,483,475],"article_tags":[],"class_list":["post-175276","article","type-article","status-publish","hentry","issues-global-framework-agreements","companies-vallourec","sectors-automotive","sectors-base-metals","sectors-chemical","sectors-energy-oil-gas-electricity-and-nuclear","sectors-mechanical-engineering"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vallourec - industriall-union<\/title>\n<meta name=\"description\" content=\"En el acuerdo se declara:En todas partes donde est\u00e1 establecido el Grupo, Vallourec aplica los convenios internacionales y las leyes nacionales y respeta\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vallourec\" \/>\n<meta property=\"og:description\" content=\"En el acuerdo se declara:En todas partes donde est\u00e1 establecido el Grupo, Vallourec aplica los convenios internacionales y las leyes nacionales y respeta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-08T18:46:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/\",\"name\":\"Vallourec - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/#website\"},\"datePublished\":\"2012-05-25T15:58:53+00:00\",\"dateModified\":\"2025-02-08T18:46:10+00:00\",\"description\":\"En el acuerdo se declara:En todas partes donde est\u00e1 establecido el Grupo, Vallourec aplica los convenios internacionales y las leyes nacionales y respeta\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/ru\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vallourec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vallourec - industriall-union","description":"En el acuerdo se declara:En todas partes donde est\u00e1 establecido el Grupo, Vallourec aplica los convenios internacionales y las leyes nacionales y respeta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/","og_locale":"es_ES","og_type":"article","og_title":"Vallourec","og_description":"En el acuerdo se declara:En todas partes donde est\u00e1 establecido el Grupo, Vallourec aplica los convenios internacionales y las leyes nacionales y respeta","og_url":"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/","og_site_name":"industriall-union","article_modified_time":"2025-02-08T18:46:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/","url":"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/","name":"Vallourec - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/#website"},"datePublished":"2012-05-25T15:58:53+00:00","dateModified":"2025-02-08T18:46:10+00:00","description":"En el acuerdo se declara:En todas partes donde est\u00e1 establecido el Grupo, Vallourec aplica los convenios internacionales y las leyes nacionales y respeta","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/vallourec-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/vallourec-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/ru\/article\/"},{"@type":"ListItem","position":3,"name":"Vallourec"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/#website","url":"https:\/\/admin.industriall-union.org\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article\/175276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=175276"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/issues?post=175276"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/companies?post=175276"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/regions?post=175276"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/sectors?post=175276"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article_tags?post=175276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}