{"id":174823,"date":"2012-12-13T16:14:20","date_gmt":"2012-12-13T16:14:20","guid":{"rendered":"https:\/\/admin.industriall-union.org\/lider-de-la-uso-asesinado-en-colombia\/"},"modified":"2025-02-08T16:41:44","modified_gmt":"2025-02-08T16:41:44","slug":"lider-de-la-uso-asesinado-en-colombia","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/","title":{"rendered":"L\u00edder de la USO asesinado en Colombia"},"content":{"rendered":"<p>En la tarde del 11 de diciembre, en el municipio colombiano de Puerto Gaitan, hombres armados asesinaron a Milton Parra Rivas, operario y electricista en Termot\u00e9cnica Coindustrial SA, subcontratista de la compa\u00f1\u00eda CEPSA, con sede en Espa\u00f1a.<\/p><p>Milton Rivas era un importante dirigente del afiliado a la IndustriALL, la Uni\u00f3n Sindical Obrera (USO), que lideraba la asamblea permanente de trabajadores en Termot\u00e9cnica. Su asesinato fue precedido de amenazas de muerte hasta el d\u00eda antes de consumarse.<\/p><p>Se produjo el d\u00eda anterior al D\u00eda de los Derechos Humanos, y es el \u00faltimo de una larga serie de ataques y amenazas a sindicalistas de la USO y de otros sindicatos en todo el pa\u00eds. Se perpetr\u00f3 horas despu\u00e9s de la firma de un Acuerdo de Libre Comercio entre la Uni\u00f3n Europea y Colombia y Per\u00fa.<\/p><p>Leif Sande, presidente de Industri Energi, afiliado noruego a la IndustriALL, se dirigi\u00f3 ayer a la plenaria del Foro de di\u00e1logo mundial sobre las futuras necesidades en materia de competencias laborales y formaci\u00f3n en la industria del petr\u00f3leo y el gas, de la OIT, en Ginebra (Suiza), y dijo:<\/p><blockquote><p>Presidente, sobre un punto de privilegio, acaba de se\u00f1al\u00e1rseme que otro sindicalista colombiano fue asesinado ayer &ndash; un miembro del sindicato de trabajadores del petr\u00f3leo &ndash; despu\u00e9s de reiteradas amenazas de muerte a los dirigentes del sindicato, aparentemente por la \u00fanica raz\u00f3n de participar en actividades sindicales. Pido que esta asamblea se una a m\u00ed para condenar este execrable acto.<\/p><\/blockquote><p>El 4 y el 15 de octubre, el secretario general de la IndustriALL Global Union envi\u00f3 cartas instando al Gobierno colombiano a tomar todas las medidas necesarias para poner fin a las pr\u00e1cticas antisindicales en Puerto Gaitan y a cesar inmediatamente la violencia contra miembros de la USO y trabajadores en huelga de Termot\u00e9cnica.<\/p><p>La realidad de hoy contrasta con la respuesta del Gobierno colombiano a esas cartas, en la que se dec\u00eda que el Gobierno es el primero en defender las libertades civiles y generar la acci\u00f3n para proteger a sus ciudadanos, de manera que las instituciones jur\u00eddicas corrijan esas potenciales amenazas y violaciones de la constituci\u00f3n.<\/p><p>El asesinato de Milton Rivas prueba la persistente cultura antisindical y la falta de protecci\u00f3n efectiva en Colombia. En 2001 fueron matados en Colombia 29 sindicalistas.<\/p><p>El Comit\u00e9 Ejecutivo de la IndustriALL Global Union resolvi\u00f3 hoy:<\/p><ul><li>Condenar categ\u00f3ricamente el asesinato como un acto de agresi\u00f3n al movimiento sindical en general y al sindicato del petr\u00f3leo en particular;<\/li><li>Enviar un mensaje de p\u00e9same y condolencias a la familia, los amigos y el sindicato de Milton Rivas Parra;<\/li><li>Expresar el continuo apoyo a la USO, a todos los afiliados colombianos a la IndustriALL y dem\u00e1s sindicatos de Colombia que sufren una violencia similar;<\/li><li>Unirse a la USO en su demanda a la Fiscal\u00eda General y a las autoridades competentes para que emprendan una investigaci\u00f3n a fondo de este crimen y se castigue a los culpables;<\/li><\/ul><p>Instar al Gobierno a que d\u00e9 plenas garant\u00edas sobre el libre ejercicio de las actividades sindicales y se respeten plenamente los convenios fundamentales de la Organizaci\u00f3n Internacional del Trabajo (OIT), ratificados por Colombia.<\/p>","protected":false},"featured_media":0,"template":"","issues":[422],"companies":[],"regions":[264],"sectors":[483],"article_tags":[],"class_list":["post-174823","article","type-article","status-publish","hentry","issues-human-trade-union-rights","regions-colombia","sectors-energy-oil-gas-electricity-and-nuclear"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u00edder de la USO asesinado en Colombia - industriall-union<\/title>\n<meta name=\"description\" content=\"En la tarde del 11 de diciembre, en el municipio colombiano de Puerto Gaitan, hombres armados asesinaron a Milton Parra Rivas, operario y electricista en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00edder de la USO asesinado en Colombia\" \/>\n<meta property=\"og:description\" content=\"En la tarde del 11 de diciembre, en el municipio colombiano de Puerto Gaitan, hombres armados asesinaron a Milton Parra Rivas, operario y electricista en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-08T16:41:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/\",\"name\":\"L\u00edder de la USO asesinado en Colombia - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2012-12-13T16:14:20+00:00\",\"dateModified\":\"2025-02-08T16:41:44+00:00\",\"description\":\"En la tarde del 11 de diciembre, en el municipio colombiano de Puerto Gaitan, hombres armados asesinaron a Milton Parra Rivas, operario y electricista en\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u00edder de la USO asesinado en Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u00edder de la USO asesinado en Colombia - industriall-union","description":"En la tarde del 11 de diciembre, en el municipio colombiano de Puerto Gaitan, hombres armados asesinaron a Milton Parra Rivas, operario y electricista en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/","og_locale":"es_ES","og_type":"article","og_title":"L\u00edder de la USO asesinado en Colombia","og_description":"En la tarde del 11 de diciembre, en el municipio colombiano de Puerto Gaitan, hombres armados asesinaron a Milton Parra Rivas, operario y electricista en","og_url":"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/","og_site_name":"industriall-union","article_modified_time":"2025-02-08T16:41:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/","url":"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/","name":"L\u00edder de la USO asesinado en Colombia - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2012-12-13T16:14:20+00:00","dateModified":"2025-02-08T16:41:44+00:00","description":"En la tarde del 11 de diciembre, en el municipio colombiano de Puerto Gaitan, hombres armados asesinaron a Milton Parra Rivas, operario y electricista en","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/lider-de-la-uso-asesinado-en-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"L\u00edder de la USO asesinado en Colombia"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article\/174823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=174823"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/issues?post=174823"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/companies?post=174823"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/regions?post=174823"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/sectors?post=174823"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article_tags?post=174823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}