{"id":174093,"date":"2013-05-02T15:12:49","date_gmt":"2013-05-02T15:12:49","guid":{"rendered":"https:\/\/admin.industriall-union.org\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/"},"modified":"2025-02-08T12:20:44","modified_gmt":"2025-02-08T12:20:44","slug":"valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/","title":{"rendered":"Valentin Urusov recibe el premio internacional de los derechos sindicales"},"content":{"rendered":"<p>&ldquo;Urusov se ha convertido en un s\u00edmbolo de la lucha por los derechos de los trabajadores y la libertad de asociaci\u00f3n en Rusia&rdquo;, dice Leif Sande, presidente del comit\u00e9 del premio y director del sindicato Industri Energi, afiliado noruego a la IndustriALL.<\/p><p>Urusov fue encarcelado por lo que muchos denominan un caso fabricado en represalia por sus exitosas tentativas de organizar a los trabajadores de las minas de diamante en la provincia septentrional de Saja en Rusia.<\/p><p>En marzo de 2013, el tribunal local de Saja (Rusia) orden\u00f3 la puesta en libertad de Valentin Urusov. Habr\u00e1 de pagar una multa y de hacer trabajos para la comunidad, en lugar de cumplir el resto de su condena de 5 a\u00f1os.<\/p><p>Mientras Urusov estaba a\u00fan en prisi\u00f3n, la IndustriALL se uni\u00f3 a la UITA para pedir al jurado que lo nominara para el Premio Internacional Arthur Svensson por la Defensa de los Derechos Sindicales de 2013, en raz\u00f3n de su valiente y encomiable labor sindical.<\/p><p>El Premio Internacional Arthur Svensson por la Defensa de los Derechos Sindicales se concede a personas o a organizaciones que han hecho notables esfuerzos para promover la labor de los sindicatos y los derechos de los trabajadores, nacional e internacionalmente.<\/p><p>La IndustriALL felicita a Valentin Urusov, heroico sindicalista ruso, al recibir este prestigioso premio internacional, y expresa su agradecimiento a todas las organizaciones y personas que contribuyeron a la campa\u00f1a por su liberaci\u00f3n de la c\u00e1rcel.<\/p>","protected":false},"featured_media":0,"template":"","issues":[420,425],"companies":[],"regions":[242],"sectors":[495],"article_tags":[],"class_list":["post-174093","article","type-article","status-publish","hentry","issues-solidarity","issues-workers-rights","regions-russia","sectors-mining"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Valentin Urusov recibe el premio internacional de los derechos sindicales - industriall-union<\/title>\n<meta name=\"description\" content=\"&ldquo;Urusov se ha convertido en un s\u00edmbolo de la lucha por los derechos de los trabajadores y la libertad de asociaci\u00f3n en Rusia&rdquo;, dice Leif\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valentin Urusov recibe el premio internacional de los derechos sindicales\" \/>\n<meta property=\"og:description\" content=\"&ldquo;Urusov se ha convertido en un s\u00edmbolo de la lucha por los derechos de los trabajadores y la libertad de asociaci\u00f3n en Rusia&rdquo;, dice Leif\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-08T12:20:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/\",\"name\":\"Valentin Urusov recibe el premio internacional de los derechos sindicales - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2013-05-02T15:12:49+00:00\",\"dateModified\":\"2025-02-08T12:20:44+00:00\",\"description\":\"&ldquo;Urusov se ha convertido en un s\u00edmbolo de la lucha por los derechos de los trabajadores y la libertad de asociaci\u00f3n en Rusia&rdquo;, dice Leif\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valentin Urusov recibe el premio internacional de los derechos sindicales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Valentin Urusov recibe el premio internacional de los derechos sindicales - industriall-union","description":"&ldquo;Urusov se ha convertido en un s\u00edmbolo de la lucha por los derechos de los trabajadores y la libertad de asociaci\u00f3n en Rusia&rdquo;, dice Leif","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/","og_locale":"es_ES","og_type":"article","og_title":"Valentin Urusov recibe el premio internacional de los derechos sindicales","og_description":"&ldquo;Urusov se ha convertido en un s\u00edmbolo de la lucha por los derechos de los trabajadores y la libertad de asociaci\u00f3n en Rusia&rdquo;, dice Leif","og_url":"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/","og_site_name":"industriall-union","article_modified_time":"2025-02-08T12:20:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/","url":"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/","name":"Valentin Urusov recibe el premio internacional de los derechos sindicales - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2013-05-02T15:12:49+00:00","dateModified":"2025-02-08T12:20:44+00:00","description":"&ldquo;Urusov se ha convertido en un s\u00edmbolo de la lucha por los derechos de los trabajadores y la libertad de asociaci\u00f3n en Rusia&rdquo;, dice Leif","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/valentin-urusov-recibe-el-premio-internacional-de-los-derechos-sindicales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/fr\/article\/"},{"@type":"ListItem","position":3,"name":"Valentin Urusov recibe el premio internacional de los derechos sindicales"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article\/174093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=174093"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/issues?post=174093"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/companies?post=174093"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/regions?post=174093"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/sectors?post=174093"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article_tags?post=174093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}