{"id":173782,"date":"2013-06-13T14:57:29","date_gmt":"2013-06-13T14:57:29","guid":{"rendered":"https:\/\/admin.industriall-union.org\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/"},"modified":"2025-02-08T11:09:31","modified_gmt":"2025-02-08T11:09:31","slug":"se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/","title":{"rendered":"Se publica informe anual de la CSI sobre violaciones de los derechos sindicales"},"content":{"rendered":"<p>Todos los a\u00f1os, la Confederaci\u00f3n Sindical Internacional (CSI), confederaci\u00f3n de centrales sindicales nacionales, pide informaci\u00f3n para recopilar datos sobre todas las violaciones de los derechos sindicales, pa\u00eds por pa\u00eds, que se publica como su Informe Anual sobre las Violaciones de los Derechos Sindicales.<\/p><p>El documento &ldquo;<a href=\"http:\/\/www.ituc-csi.org\/paises-en-situacion-de-riesgo?lang=es\">Pa\u00edses en situaci\u00f3n de riesgo: Informe 2013 de la CSI sobre las violaciones de los derechos sindicales<\/a>&rdquo; fue publicado oficialmente el d\u00eda 12 de junio, en la Conferencia Internacional del Trabajo.<\/p><p>El informe se\u00f1alado revela datos clave respecto a 87 pa\u00edses, centr\u00e1ndose especialmente en siete pa\u00edses en situaci\u00f3n de riesgo, donde la existencia tanto de los sindicatos como de otras instituciones democr\u00e1ticas corre extremo peligro: Birmania\/Myanmar, Bahrein, Fiji, Guatemala, Swazilandia, Zimbabwe y Georgia.<\/p><p>Con motivo de la publicaci\u00f3n del informe, Sharan Burrow, Secretaria General de la CSI, dijo lo siguiente:<\/p><p>&ldquo;Cientos de millones de trabajadores y trabajadoras, en pa\u00edses en v\u00edas de desarrollo o industrializados, ven denegados sus derechos fundamentales de libertad de sindicaci\u00f3n y de negociaci\u00f3n colectiva.&rdquo;<\/p><p>&nbsp;&ldquo;Para muchos trabajadores y trabajadoras, especialmente aquellos que tienen un empleo precario, esta injusticia contra los trabajadores causa estragos en sus vidas, ya que se ven obligados a trabajar largas jornadas en condiciones peligrosas o insalubres y con salarios tan bajos que no pueden subsistir, ni mantener a sus familias adecuadamente. El incumplimiento de los derechos de los trabajadores ha incrementado la desigualdad en todo el mundo, y esa desigualdad no s\u00f3lo ha contribuido a provocar la crisis econ\u00f3mica mundial, sino tambi\u00e9n frena la recuperaci\u00f3n&rdquo;.<\/p><p>Ver el informe completo en el sitio web de la CSI, aqu\u00ed: (<a href=\"http:\/\/www.ituc-csi.org\/paises-en-situacion-de-riesgo?lang=es\">http:\/\/www.ituc-csi.org\/paises-en-situacion-de-riesgo?lang=es<\/a>)<\/p>","protected":false},"featured_media":0,"template":"","issues":[422],"companies":[],"regions":[],"sectors":[],"article_tags":[],"class_list":["post-173782","article","type-article","status-publish","hentry","issues-human-trade-union-rights"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Se publica informe anual de la CSI sobre violaciones de los derechos sindicales - industriall-union<\/title>\n<meta name=\"description\" content=\"Todos los a\u00f1os, la Confederaci\u00f3n Sindical Internacional (CSI), confederaci\u00f3n de centrales sindicales nacionales, pide informaci\u00f3n para recopilar datos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se publica informe anual de la CSI sobre violaciones de los derechos sindicales\" \/>\n<meta property=\"og:description\" content=\"Todos los a\u00f1os, la Confederaci\u00f3n Sindical Internacional (CSI), confederaci\u00f3n de centrales sindicales nacionales, pide informaci\u00f3n para recopilar datos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-08T11:09:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/\",\"name\":\"Se publica informe anual de la CSI sobre violaciones de los derechos sindicales - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2013-06-13T14:57:29+00:00\",\"dateModified\":\"2025-02-08T11:09:31+00:00\",\"description\":\"Todos los a\u00f1os, la Confederaci\u00f3n Sindical Internacional (CSI), confederaci\u00f3n de centrales sindicales nacionales, pide informaci\u00f3n para recopilar datos\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Se publica informe anual de la CSI sobre violaciones de los derechos sindicales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Se publica informe anual de la CSI sobre violaciones de los derechos sindicales - industriall-union","description":"Todos los a\u00f1os, la Confederaci\u00f3n Sindical Internacional (CSI), confederaci\u00f3n de centrales sindicales nacionales, pide informaci\u00f3n para recopilar datos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/","og_locale":"es_ES","og_type":"article","og_title":"Se publica informe anual de la CSI sobre violaciones de los derechos sindicales","og_description":"Todos los a\u00f1os, la Confederaci\u00f3n Sindical Internacional (CSI), confederaci\u00f3n de centrales sindicales nacionales, pide informaci\u00f3n para recopilar datos","og_url":"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/","og_site_name":"industriall-union","article_modified_time":"2025-02-08T11:09:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/","url":"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/","name":"Se publica informe anual de la CSI sobre violaciones de los derechos sindicales - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2013-06-13T14:57:29+00:00","dateModified":"2025-02-08T11:09:31+00:00","description":"Todos los a\u00f1os, la Confederaci\u00f3n Sindical Internacional (CSI), confederaci\u00f3n de centrales sindicales nacionales, pide informaci\u00f3n para recopilar datos","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/se-publica-informe-anual-de-la-csi-sobre-violaciones-de-los-derechos-sindicales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"Se publica informe anual de la CSI sobre violaciones de los derechos sindicales"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article\/173782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=173782"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/issues?post=173782"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/companies?post=173782"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/regions?post=173782"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/sectors?post=173782"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article_tags?post=173782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}