{"id":173601,"date":"2013-07-03T15:09:20","date_gmt":"2013-07-03T15:09:20","guid":{"rendered":"https:\/\/admin.industriall-union.org\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/"},"modified":"2025-02-08T10:16:41","modified_gmt":"2025-02-08T10:16:41","slug":"clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/","title":{"rendered":"Clase trabajadores brasilera se  organiza en el D\u00eda Nacional de Lucha"},"content":{"rendered":"<p>El D\u00eda Nacional de Lucha que se realizar\u00e1&nbsp; junto &nbsp;a movimientos sociales y populares, busca una salida positiva a la actual situaci\u00f3n. A pesar de que las movilizaciones de millones de personas en todo el pa\u00eds, que contaron con el apoyo y participaci\u00f3n del movimiento sindical,&nbsp; que pusieron en el centro de la coyuntura la reivindicaci\u00f3n de la reducci\u00f3n de tarifas y&nbsp; calidad en el transporte p\u00fablico, salud, y educaci\u00f3n p\u00fablica y el descontento con la forma como las instituciones pol\u00edticas vienen funcionando, tuvo resultados concretos puesto que se conquist\u00f3 la reducci\u00f3n de tarifas en el transporte p\u00fablico, en la mayor\u00eda de las capitales y otras ciudades, sin embargo la cuesti\u00f3n de la reforma pol\u00edtica sigue paralizada en un debate viciado en el Parlamento y debe ser puesta en un amplio debate en la sociedad.<\/p><p>En la jornada de lucha demandar\u00e1n contra el Proyecto de Ley 4330, de tercerizaci\u00f3n, que retira derechos de los trabajadores brasileros y precariza a\u00fan m\u00e1s las relaciones de trabajo en Brasil; Este proyecto precisa ser sacado inmediatamente de la pauta del Congreso Nacional.<\/p><p>En esta materia y dado que el 9 de julio esta agendada la votaci\u00f3n del Congreso (Comisi\u00f3n de Constituci\u00f3n y Justicia) de este proyecto de &nbsp;ley 4330, las organizaciones sindicales organizar\u00e1n &nbsp;el 4 de julio una jornada de advertencia con paralizaciones en las principales categor\u00edas,&nbsp; por la derogaci\u00f3n de este proyecto de ley. Y posteriormente para el 11 de julio, &nbsp;continuar &nbsp;con manifestaciones, paralizaciones y huelgas.<\/p><p>En la jornada de lucha exigir\u00e1n que las reducciones de tarifa del transporte no sean acompa\u00f1adas de cualquier corte de gastos sociales. El 10% de presupuesto de uni\u00f3n para la salud p\u00fablica; el 10% del PIB para la educaci\u00f3n p\u00fablica, los &ldquo;fondos p\u00fablicos son s\u00f3lo para el sector p\u00fablico&rdquo;; fin del factor de pensi\u00f3n; 40 horas semanales sin reducci\u00f3n de salario; Reforma Agraria y la suspensi\u00f3n de las subastas de petr\u00f3leo.<\/p><p>Asimismo demandar\u00e1n tambi\u00e9n en apoyo a los movimientos sociales,&nbsp; la lucha por la democratizaci\u00f3n de los medios, y por una reforma pol\u00edtica que pase por un plebiscito popular.<\/p><p>La CUT, que agrupa a algunas organizaciones sindicales afiliadas a IndustriALL, considera que los recursos para invertir en la mejor\u00eda de los servicios p\u00fablicos existen: billones de recursos p\u00fablicos fueron dados a los empresarios en forma de exoneraciones, exenciones y cr\u00e9ditos p\u00fablicos subsidiarios sin exigir contrapartes; billones est\u00e1n destinados al super\u00e1vit primario para pagar la deuda.<\/p><p>Por ende la CUT, orienta que sean priorizadas paralizaciones en diferentes ramas y categor\u00edas&nbsp; que pueden y deben incorporar sus reivindicaciones espec\u00edficas en este movimiento en conjunto.<\/p><p>En tanto, Miguel Torres presidente de la CNTM de Forca Sindical, afiliada a IndustriALL, se\u00f1al\u00f3 que &ldquo;estamos en un momento importante de la vida del Pa\u00eds, de importantes cambios efectivos en la econom\u00eda, en la direcci\u00f3n de los recursos p\u00fablicos y la definici\u00f3n de las prioridades sociales y pol\u00edticas&rdquo;. Agreg\u00f3 que &ldquo;los trabajadores son los protagonistas de estos movimientos, pues son los verdaderos constructores de la Naci\u00f3n, y siempre estuvieron en las calles protestando y reivindicando derechos, participaci\u00f3n en el escenario pol\u00edtico y en mejoras para la vida de la poblaci\u00f3n&rdquo;.<\/p>","protected":false},"featured_media":0,"template":"","issues":[],"companies":[],"regions":[261],"sectors":[],"article_tags":[],"class_list":["post-173601","article","type-article","status-publish","hentry","regions-brazil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Clase trabajadores brasilera se organiza en el D\u00eda Nacional de Lucha - industriall-union<\/title>\n<meta name=\"description\" content=\"El D\u00eda Nacional de Lucha que se realizar\u00e1&nbsp; junto &nbsp;a movimientos sociales y populares, busca una salida positiva a la actual situaci\u00f3n. A pesar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clase trabajadores brasilera se organiza en el D\u00eda Nacional de Lucha\" \/>\n<meta property=\"og:description\" content=\"El D\u00eda Nacional de Lucha que se realizar\u00e1&nbsp; junto &nbsp;a movimientos sociales y populares, busca una salida positiva a la actual situaci\u00f3n. A pesar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-08T10:16:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/\",\"name\":\"Clase trabajadores brasilera se organiza en el D\u00eda Nacional de Lucha - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2013-07-03T15:09:20+00:00\",\"dateModified\":\"2025-02-08T10:16:41+00:00\",\"description\":\"El D\u00eda Nacional de Lucha que se realizar\u00e1&nbsp; junto &nbsp;a movimientos sociales y populares, busca una salida positiva a la actual situaci\u00f3n. A pesar\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Clase trabajadores brasilera se organiza en el D\u00eda Nacional de Lucha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Clase trabajadores brasilera se organiza en el D\u00eda Nacional de Lucha - industriall-union","description":"El D\u00eda Nacional de Lucha que se realizar\u00e1&nbsp; junto &nbsp;a movimientos sociales y populares, busca una salida positiva a la actual situaci\u00f3n. A pesar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/","og_locale":"es_ES","og_type":"article","og_title":"Clase trabajadores brasilera se organiza en el D\u00eda Nacional de Lucha","og_description":"El D\u00eda Nacional de Lucha que se realizar\u00e1&nbsp; junto &nbsp;a movimientos sociales y populares, busca una salida positiva a la actual situaci\u00f3n. A pesar","og_url":"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/","og_site_name":"industriall-union","article_modified_time":"2025-02-08T10:16:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/","url":"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/","name":"Clase trabajadores brasilera se organiza en el D\u00eda Nacional de Lucha - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2013-07-03T15:09:20+00:00","dateModified":"2025-02-08T10:16:41+00:00","description":"El D\u00eda Nacional de Lucha que se realizar\u00e1&nbsp; junto &nbsp;a movimientos sociales y populares, busca una salida positiva a la actual situaci\u00f3n. A pesar","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/clase-trabajadores-brasilera-se-organiza-en-el-dia-nacional-de-lucha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"Clase trabajadores brasilera se organiza en el D\u00eda Nacional de Lucha"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article\/173601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=173601"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/issues?post=173601"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/companies?post=173601"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/regions?post=173601"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/sectors?post=173601"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article_tags?post=173601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}