{"id":155530,"date":"2022-02-01T06:16:12","date_gmt":"2022-02-01T06:16:12","guid":{"rendered":"https:\/\/admin.industriall-union.org\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/"},"modified":"2025-01-28T04:56:03","modified_gmt":"2025-01-28T04:56:03","slug":"el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/","title":{"rendered":"El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical"},"content":{"rendered":"<p>Los afiliados de IndustriALL Global Union en Nigeria se han comprometido a luchar contra los aumentos de los precios de la gasolina que, seg\u00fan ellos, afectar\u00e1n los ingresos de sus miembros y profundizar\u00e1n la pobreza.<\/p><p>El Sindicato Nacional de Trabajadores del Petr\u00f3leo y el Gas Natural (NUPENG) y la Asociaci\u00f3n de Personal Directivo del Petr\u00f3leo y el Gas Natural (PENGASSAN) est\u00e1n pidiendo al gobierno que industrialice la econom\u00eda resucitando las refiner\u00edas locales. Seg\u00fan los sindicatos, las refiner\u00edas locales ayudar\u00e1n a mitigar los efectos de la fluctuaci\u00f3n de los precios del petr\u00f3leo, crear\u00e1n empleos dignos y aumentar\u00e1n los ingresos del pa\u00eds.<\/p><p>Previamente, las autoridades hab\u00edan anunciado un aumento del precio de la gasolina de 320 a 340 nairas por litro (5 centavos de d\u00f3lar estadounidense). Sin embargo, el 24 de enero, el gobierno anunci\u00f3 que revertir\u00eda la decisi\u00f3n de cara a las manifestaciones nacionales planificadas y organizadas por sindicatos y organizaciones de la sociedad civil.<\/p><blockquote><p>&ldquo;La suspensi\u00f3n del aumento del precio de la gasolina no es una victoria total porque no cambia las condiciones sociales y econ\u00f3micas de los trabajadores nigerianos. El desempleo es alto y la inflaci\u00f3n est\u00e1 aumentando. Los trabajadores necesitan un colch\u00f3n de protecci\u00f3n social que incluya un transporte p\u00fablico asequible y el desarrollo de la infraestructura&rdquo;,<\/p><\/blockquote><p>expres\u00f3 Olawale Afolabi, secretario general del NUPENG.<\/p><blockquote><p>&ldquo;En el futuro, continuaremos interpelando al gobierno sobre temas tan delicados como la garant\u00eda de la refinaci\u00f3n local de petr\u00f3leo, la creaci\u00f3n de empleos sostenibles y el suministro de gasolina a un precio asequible&rdquo;.<\/p><\/blockquote><p>declar\u00f3 Ayuba Wabba, secretario general del Congreso del Trabajo de Nigeria.<\/p><p>El Congreso de Sindicatos de Nigeria (TUC) tambi\u00e9n insiste en la &ldquo;revitalizaci\u00f3n de las refiner\u00edas existentes, la creaci\u00f3n de otras nuevas, sobre todo modulares, y la vigilancia eficaz de las fronteras para detener el contrabando de productos derivados del petr\u00f3leo&rdquo;.<br \/>&nbsp;<br \/>Durante varios a\u00f1os, los sindicatos han hecho campa\u00f1a contra la &ldquo;maldici\u00f3n de los recursos&rdquo; en Nigeria, donde las reservas de petr\u00f3leo y gas no han ayudado a la econom\u00eda ni han puesto fin a la pobreza.<br \/>&nbsp;<br \/>Paule France Ndessomin, secretaria regional de IndustriALL para \u00c1frica subsahariana, expres\u00f3:<\/p><blockquote><p>&ldquo;Los trabajadores y las comunidades en Nigeria esperan que el gobierno proporcione gasolina asequible y no quieren verse agobiados por aumentos que suelen ser el resultado de la corrupci\u00f3n. Los trabajadores nigerianos deben disfrutar de los beneficios que provienen de las vastas cantidades de reservas de petr\u00f3leo y gas del pa\u00eds, y esto incluye poder comprar gasolina asequible y refinada localmente&rdquo;.<\/p><\/blockquote><p><em>Foto: Estaci\u00f3n de servicio flotante de gasolina y di\u00e9sel en el delta del N\u00edger, Stakeholder Democracy<\/em><\/p>","protected":false},"featured_media":0,"template":"","issues":[399,425],"companies":[],"regions":[343],"sectors":[483],"article_tags":[],"class_list":["post-155530","article","type-article","status-publish","hentry","issues-union-building","issues-workers-rights","regions-nigeria","sectors-energy-oil-gas-electricity-and-nuclear"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical - industriall-union<\/title>\n<meta name=\"description\" content=\"Los afiliados de IndustriALL Global Union en Nigeria se han comprometido a luchar contra los aumentos de los precios de la gasolina que, seg\u00fan ellos,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical\" \/>\n<meta property=\"og:description\" content=\"Los afiliados de IndustriALL Global Union en Nigeria se han comprometido a luchar contra los aumentos de los precios de la gasolina que, seg\u00fan ellos,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T04:56:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/\",\"name\":\"El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/#website\"},\"datePublished\":\"2022-02-01T06:16:12+00:00\",\"dateModified\":\"2025-01-28T04:56:03+00:00\",\"description\":\"Los afiliados de IndustriALL Global Union en Nigeria se han comprometido a luchar contra los aumentos de los precios de la gasolina que, seg\u00fan ellos,\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/ru\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical - industriall-union","description":"Los afiliados de IndustriALL Global Union en Nigeria se han comprometido a luchar contra los aumentos de los precios de la gasolina que, seg\u00fan ellos,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/","og_locale":"es_ES","og_type":"article","og_title":"El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical","og_description":"Los afiliados de IndustriALL Global Union en Nigeria se han comprometido a luchar contra los aumentos de los precios de la gasolina que, seg\u00fan ellos,","og_url":"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/","og_site_name":"industriall-union","article_modified_time":"2025-01-28T04:56:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/","url":"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/","name":"El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/#website"},"datePublished":"2022-02-01T06:16:12+00:00","dateModified":"2025-01-28T04:56:03+00:00","description":"Los afiliados de IndustriALL Global Union en Nigeria se han comprometido a luchar contra los aumentos de los precios de la gasolina que, seg\u00fan ellos,","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/el-gobierno-nigeriano-suspende-el-aumento-del-precio-de-la-gasolina-frente-a-la-movilizacion-sindical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/ru\/article\/"},{"@type":"ListItem","position":3,"name":"El gobierno nigeriano suspende el aumento del precio de la gasolina frente a la movilizaci\u00f3n sindical"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/#website","url":"https:\/\/admin.industriall-union.org\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article\/155530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=155530"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/issues?post=155530"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/companies?post=155530"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/regions?post=155530"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/sectors?post=155530"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article_tags?post=155530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}