{"id":153619,"date":"2022-12-15T09:07:54","date_gmt":"2022-12-15T09:07:54","guid":{"rendered":"https:\/\/admin.industriall-union.org\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/"},"modified":"2025-01-27T23:01:03","modified_gmt":"2025-01-27T23:01:03","slug":"nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas","status":"publish","type":"article","link":"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/","title":{"rendered":"Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas"},"content":{"rendered":"<p>A \u00faltima hora del viernes 2 de diciembre, despu\u00e9s de una reuni\u00f3n t\u00e9cnica de una semana celebrada en la sede de la OIT en Ginebra, las negociaciones entre representantes de los trabajadores, Gobiernos y empresarios concluyeron en&nbsp;<a href=\"https:\/\/www.ilo.org\/wcmsp5\/groups\/public\/---ed_dialogue\/---sector\/documents\/meetingdocument\/wcms_863414.pdf\">un acuerdo<\/a>&nbsp;sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas.<\/p><p>Las reuniones de este tipo proporcionan orientaci\u00f3n sobre c\u00f3mo abordar los problemas de un sector. Son particularmente importantes frente al surgimiento de nuevos sectores o a medida que aquellos que ya existen se enfrentan a cambios importantes debido a una doble transici\u00f3n: la clim\u00e1tica y la tecnol\u00f3gica. La industria del petr\u00f3leo y el gas, una de las principales contribuyentes a las emisiones de gases de efecto invernadero, se ver\u00e1 muy afectada por la necesidad de descarbonizaci\u00f3n. Para los sindicatos, es esencial que este proceso transcurra de una manera planificada y estructurada, de modo que se puedan crear nuevos puestos de trabajo antes de que desaparezcan los antiguos.<\/p><p>La delegaci\u00f3n sindical estuvo formada por expertos del sector del petr\u00f3leo y el gas elegidos democr\u00e1ticamente para representar a sindicatos de&nbsp;Estados Unidos, Brasil, Colombia, Nigeria, Irak, Noruega, Australia e Indonesia. Recibi\u00f3 apoyo de la CSI, IndustriALL Global Union e industriAll European Union.<\/p><p>La oficina de la OIT elabor\u00f3 un&nbsp;<a href=\"https:\/\/www.ilo.org\/wcmsp5\/groups\/public\/---ed_dialogue\/---sector\/documents\/publication\/wcms_859846.pdf\">informe<\/a>&nbsp;que sirvi\u00f3 de base para el debate. Al comienzo de la semana, se plantearon preguntas sobre desaf\u00edos, oportunidades, buenas pr\u00e1cticas y demandas. Los negociadores presentaron sus puntos de vista y sus principales demandas. A partir de estos aportes, la oficina de la OIT redact\u00f3 una primera versi\u00f3n del documento, y las partes negociaron ciertas modificaciones a lo largo de la semana.<\/p><p>Los representantes de los trabajadores presentaron las siguientes demandas clave:<\/p><ul><li>Empleos decentes y sindicalizados en el futuro, negociados a trav\u00e9s de un di\u00e1logo social que incluya a los sindicatos en el proceso de toma de decisiones.<\/li><li>Que se hiciera menci\u00f3n al alto nivel de tercerizaci\u00f3n en la industria y a la responsabilidad que deben asumir los Gobiernos al desarrollar planes energ\u00e9ticos, al igual que los empleadores al realizar la diligencia debida en sus cadenas de suministro.<\/li><li>Un mecanismo de financiaci\u00f3n para una Transici\u00f3n Justa en el sector.<\/li><li>Inversi\u00f3n en planes energ\u00e9ticos, a mediano y largo plazo, que incluyan el desarrollo de competencias y la reconversi\u00f3n profesional.<\/li><\/ul><p>La delegaci\u00f3n sindical se mostr\u00f3 insatisfecha tanto con el proceso de la reuni\u00f3n como con el resultado. Se desaprovech\u00f3 la oportunidad de abordar muchas cuestiones apremiantes, en particular el problema de los trabajadores tercerizados. Esto se debi\u00f3 a la falta de compromiso de los empleadores. Ninguna de las empresas principales del sector asisti\u00f3 a la reuni\u00f3n, al tiempo que el negociador l\u00edder de los empleadores, proveniente de la Organizaci\u00f3n Internacional de Empleadores (OIE), carec\u00eda de experiencia espec\u00edfica en el sector, ya que este organismo negocia acuerdos en los sectores del turismo, la educaci\u00f3n, la agricultura, el transporte y la energ\u00eda, entre otros.<\/p><p>Debido a que los resultados no fueron tan prescriptivos como los sindicatos esperaban, la posibilidad de desarrollar una gu\u00eda de Transici\u00f3n Justa espec\u00edfica para el sector se plantear\u00e1 despu\u00e9s de la reuni\u00f3n del Consejo de Administraci\u00f3n de la OIT el pr\u00f3ximo verano.<\/p><p><img decoding=\"async\" alt=\"\" src=\"\" style=\"width: 600px;height: 338px\" \/><\/p><p>Diana Junquera Curiel, directora del sector energ\u00e9tico y de Transici\u00f3n Justa de IndustriALL, expres\u00f3:<\/p><blockquote><p>&ldquo;Cuando se trata de una Transici\u00f3n Justa en esta industria, las preocupaciones de los trabajadores incluyen la financiaci\u00f3n de la transici\u00f3n, la protecci\u00f3n social y la calidad y la cantidad de empleos decentes que estar\u00e1n disponibles. Si la transici\u00f3n no se lleva a cabo a trav\u00e9s del di\u00e1logo social, con protecci\u00f3n social, negociaci\u00f3n colectiva e inclusi\u00f3n, el futuro ser\u00e1 insostenible para todos&rdquo;.<\/p><\/blockquote><p>En su declaraci\u00f3n final, el presidente del grupo de representantes de trabajadores, Mike Smith, del USW, declar\u00f3:<\/p><blockquote><p>&ldquo;Nos complace haber llegado a un acuerdo sobre este documento despu\u00e9s de una semana de s\u00f3lidas negociaciones. Confiamos en que las conclusiones ser\u00e1n un paso adelante en el largo camino hacia una Transici\u00f3n Justa en el sector del petr\u00f3leo y el gas, y que se mantenga una industria sana y productiva que facilite la creaci\u00f3n de empleos decentes que reemplacen los puestos de trabajo que se pierden por otros de igual o mejor valor.<\/p><\/blockquote><p>Lamentamos que en este documento no se mencione a los trabajadores tercerizados. Es una gran preocupaci\u00f3n para nosotros que la tercerizaci\u00f3n sea tan frecuente en el sector del petr\u00f3leo y el gas, que esta pr\u00e1ctica socave las condiciones de trabajo y que las personas contratadas bajo esta modalidad carezcan de una voz institucional para abordar sus preocupaciones.<\/p><p>Seguiremos trabajando para garantizar que todos los trabajadores de la industria del petr\u00f3leo y el gas, ya sean empleados directos o tercerizados, gocen de libertad sindical, de salud y seguridad laboral, y de buenas condiciones de trabajo logradas a trav\u00e9s de convenios colectivos&rdquo;.<\/p>","protected":false},"featured_media":0,"template":"","issues":[390,423],"companies":[],"regions":[],"sectors":[483],"article_tags":[],"class_list":["post-153619","article","type-article","status-publish","hentry","issues-future-of-work","issues-ilo-watch","sectors-energy-oil-gas-electricity-and-nuclear"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas - industriall-union<\/title>\n<meta name=\"description\" content=\"A \u00faltima hora del viernes 2 de diciembre, despu\u00e9s de una reuni\u00f3n t\u00e9cnica de una semana celebrada en la sede de la OIT en Ginebra, las negociaciones entre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas\" \/>\n<meta property=\"og:description\" content=\"A \u00faltima hora del viernes 2 de diciembre, despu\u00e9s de una reuni\u00f3n t\u00e9cnica de una semana celebrada en la sede de la OIT en Ginebra, las negociaciones entre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T23:01:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/\",\"name\":\"Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2022-12-15T09:07:54+00:00\",\"dateModified\":\"2025-01-27T23:01:03+00:00\",\"description\":\"A \u00faltima hora del viernes 2 de diciembre, despu\u00e9s de una reuni\u00f3n t\u00e9cnica de una semana celebrada en la sede de la OIT en Ginebra, las negociaciones entre\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\/\/admin.industriall-union.org\/article\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas - industriall-union","description":"A \u00faltima hora del viernes 2 de diciembre, despu\u00e9s de una reuni\u00f3n t\u00e9cnica de una semana celebrada en la sede de la OIT en Ginebra, las negociaciones entre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/","og_locale":"es_ES","og_type":"article","og_title":"Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas","og_description":"A \u00faltima hora del viernes 2 de diciembre, despu\u00e9s de una reuni\u00f3n t\u00e9cnica de una semana celebrada en la sede de la OIT en Ginebra, las negociaciones entre","og_url":"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/","og_site_name":"industriall-union","article_modified_time":"2025-01-27T23:01:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/","url":"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/","name":"Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2022-12-15T09:07:54+00:00","dateModified":"2025-01-27T23:01:03+00:00","description":"A \u00faltima hora del viernes 2 de diciembre, despu\u00e9s de una reuni\u00f3n t\u00e9cnica de una semana celebrada en la sede de la OIT en Ginebra, las negociaciones entre","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/nuevo-acuerdo-de-la-oit-sobre-el-futuro-del-trabajo-en-el-sector-del-petroleo-y-el-gas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/admin.industriall-union.org\/article\/"},{"@type":"ListItem","position":3,"name":"Nuevo acuerdo de la OIT sobre el futuro del trabajo en el sector del petr\u00f3leo y el gas"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article\/153619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/article"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=153619"}],"wp:term":[{"taxonomy":"issues","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/issues?post=153619"},{"taxonomy":"companies","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/companies?post=153619"},{"taxonomy":"regions","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/regions?post=153619"},{"taxonomy":"sectors","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/sectors?post=153619"},{"taxonomy":"article_tags","embeddable":true,"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/article_tags?post=153619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}