{"id":202902,"date":"2009-06-30T14:55:00","date_gmt":"2009-06-30T14:55:00","guid":{"rendered":"https:\/\/admin.industriall-union.org\/archive\/imf\/articulo-2-mision-de-la-federacion\/"},"modified":"2025-01-31T10:34:24","modified_gmt":"2025-01-31T10:34:24","slug":"articulo-2-mision-de-la-federacion","status":"publish","type":"archive_imf","link":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/","title":{"rendered":"ARTICULO 2 &#8211; MISION DE LA FEDERACION"},"content":{"rendered":"<ol><li>Para alcanzar estos objetivos, la FITIM est\u00e1 empe\u00f1ada en edificar un movimiento sindical internacional fuerte, capaz de representar y fomentar efectivamente los intereses de los trabajadores, frente a una econom\u00eda global en continua expansi\u00f3n, que todav\u00eda tiene que abarcar, por no decir reconocer, adoptar y aplicar los derechos de los trabajadores.<\/li><li>La FITIM afirma que s\u00f3lo mediante los sindicatos y la pr\u00e1ctica de la negociaci\u00f3n colectiva pueden alcanzarse los objetivos de seguridad social y constante progreso. Por lo tanto, la FITIM lucha por todos los trabajadores en su deseo de libertad sindical para formar sus propios sindicatos, el derecho a la negociaci\u00f3n colectiva, el derecho a concertar convenios colectivos y el derecho de huelga para lograr sus demandas.<\/li><li>La FITIM apoya tambi\u00e9n a todos sus sindicatos afiliados, particularmente en pa\u00edses en desarrollo, en sus esfuerzos por lograr niveles de vida m\u00e1s altos para los trabajadores y promover el desarrollo democr\u00e1tico, econ\u00f3mico y social.<\/li><li>La FITIM lucha tambi\u00e9n por todas las dem\u00e1s normas laborales conexas reconocidas internacionalmente, como el derecho a un salario m\u00ednimo vital, a condiciones de trabajo seguras y sanas, por la prohibici\u00f3n de la discriminaci\u00f3n y la prohibici\u00f3n del trabajo infantil y del trabajo forzoso.<\/li><li>La FITIM est\u00e1 dispuesta a hacer causa com\u00fan con otras organizaciones sindicales independientes, aut\u00f3nomas y democr\u00e1ticas, y en particular la Confederaci\u00f3n Sindical Internacional y otras Federaciones Sindicales Internacionales, para alcanzar objetivos sindicales internacionales. Trata de trabajar con organizaciones no gubernamentales que comparten el empe\u00f1o en promover los derechos de los sindicatos y otros derechos humanos.<\/li><li>Entre las actividades de la FITIM para alcanzar esos objetivos figuran las siguientes: <ol type=\"A\"><li>Apoyar a los metal\u00fargicos en sus esfuerzos por organizarse en todas partes, especialmente en los pa\u00edses en desarrollo y en todos los pa\u00edses donde est\u00e1n amenazadas la libertad sindical y la existencia de sindicatos libres.<\/li><li>Expresar activamente las posiciones de los trabajadores metal\u00fargicos sobre posibles cuestiones sindicales, pol\u00edticas, sociales y econ\u00f3micas internacionales que conciernen a los trabajadores metal\u00fargicos en el mundo entero. Esa participaci\u00f3n comprende la presencia y la actuaci\u00f3n en foros internacionales pertinentes, como la Organizaci\u00f3n Mundial del Comercio, la Organizaci\u00f3n de Cooperaci\u00f3n y Desarrollo Econ\u00f3micos, la Confederaci\u00f3n Sindical Internacional, etc.<\/li><li>Actuar de catalizador, depositario y centro de intercambio de informaci\u00f3n y de material para los afiliados que lo necesitan en la realizaci\u00f3n de esos objetivos.<\/li><li>Proporcionar apoyo moral y pr\u00e1ctico y dirigir la elaboraci\u00f3n de estrategias creadoras e innovadoras para ayudar en conflictos econ\u00f3micos, pol\u00edticos y sociales.<\/li><\/ol><\/li><\/ol>","protected":false},"featured_media":0,"template":"","class_list":["post-202902","archive_imf","type-archive_imf","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ARTICULO 2 - MISION DE LA FEDERACION - industriall-union<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARTICULO 2 - MISION DE LA FEDERACION\" \/>\n<meta property=\"og:description\" content=\"Para alcanzar estos objetivos, la FITIM est\u00e1 empe\u00f1ada en edificar un movimiento sindical internacional fuerte, capaz de representar y fomentar efectivamente los intereses de los trabajadores, frente a una econom\u00eda global en continua expansi\u00f3n, que todav\u00eda tiene que abarcar, por no decir reconocer, adoptar y aplicar los derechos de los trabajadores. La FITIM afirma que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T10:34:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/\",\"name\":\"ARTICULO 2 - MISION DE LA FEDERACION - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2009-06-30T14:55:00+00:00\",\"dateModified\":\"2025-01-31T10:34:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archive Imf\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/archive\/imf\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ARTICULO 2 &#8211; MISION DE LA FEDERACION\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ARTICULO 2 - MISION DE LA FEDERACION - industriall-union","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/","og_locale":"es_ES","og_type":"article","og_title":"ARTICULO 2 - MISION DE LA FEDERACION","og_description":"Para alcanzar estos objetivos, la FITIM est\u00e1 empe\u00f1ada en edificar un movimiento sindical internacional fuerte, capaz de representar y fomentar efectivamente los intereses de los trabajadores, frente a una econom\u00eda global en continua expansi\u00f3n, que todav\u00eda tiene que abarcar, por no decir reconocer, adoptar y aplicar los derechos de los trabajadores. La FITIM afirma que [&hellip;]","og_url":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/","og_site_name":"industriall-union","article_modified_time":"2025-01-31T10:34:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/","url":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/","name":"ARTICULO 2 - MISION DE LA FEDERACION - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2009-06-30T14:55:00+00:00","dateModified":"2025-01-31T10:34:24+00:00","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/articulo-2-mision-de-la-federacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Archive Imf","item":"https:\/\/admin.industriall-union.org\/fr\/archive\/imf\/"},{"@type":"ListItem","position":3,"name":"ARTICULO 2 &#8211; MISION DE LA FEDERACION"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/archive_imf\/202902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/archive_imf"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/archive_imf"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=202902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}