{"id":199175,"date":"2012-04-23T17:03:00","date_gmt":"2012-04-23T17:03:00","guid":{"rendered":"https:\/\/admin.industriall-union.org\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/"},"modified":"2025-01-31T08:33:07","modified_gmt":"2025-01-31T08:33:07","slug":"el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado","status":"publish","type":"archive_imf","link":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/","title":{"rendered":"El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado"},"content":{"rendered":"<p>SERBIA\/KOSOVO: Tras pasar 28 d\u00edas en la c\u00e1rcel, primero aislado y luego en una celda con otros 15 presos, Hasan Abazi, presidente del Sindicato Independiente de Trabajadores Metal\u00fargicos de Kosovo, afiliado a la FITIM, fue liberado el 20 de abril, a mediod\u00eda, previo pago de una fianza de 20.000 \u20ac.<\/p><p>El presidente del sindicato, que fue detenido el 28 de marzo en el sur de Serbia cuando viajaba a Zagreb (Croatia), para asistir a una reuni\u00f3n de tres federaciones sindicales europeas, FEM., EMF, EMCEF y ETUF-TCL, est\u00e1 ya de regreso en Kosovo. <\/p><p>Su detenci\u00f3n gener\u00f3 protestas inmediatas y masivas en el mundo entero, con inclusi\u00f3n de varias intervenciones diplom\u00e1ticas de alto nivel, y suscit\u00f3 serias preocupaciones en la comunidad internacional sobre la aplicaci\u00f3n del imperio de la ley y el respeto de derechos humanos fundamentales en Serbia.<\/p><p>Complementando un llamamiento a la solidaridad de sindicatos de todo el mundo, la FITIM lanz\u00f3 una campa\u00f1a en Labourstart, como resultado de la cual se enviaron a las autoridades serbias cerca de 8.000 cartas de protesta solicitando la liberaci\u00f3n de Hasan. <\/p><p>Agrupaciones laborales y organizaciones de derechos humanos aumentaron tambi\u00e9n la presi\u00f3n sobre el Gobierno serbio a trav\u00e9s de la UE, embajadas y otros canales diplom\u00e1ticos.<\/p><p>&quot;La FITIM, la ICEM y la FITTVC y sus organizaciones hermanas europeas est\u00e1n muy agradecidas a todas las personas y organizaciones que se han unido en la campa\u00f1a de LabourStart para liberarle. La movilizaci\u00f3n mundial y la presi\u00f3n ejercida sobre las autoridades serbias contra la vergonzosa detenci\u00f3n de Hasan han sido decisivas para sacarle de la c\u00e1rcel&#8221;, dijo Jyrki Raina, secretario general de la FITIM.<\/p><p>V\u00e9ase la <a href=\"..\/files\/12033013330966\/Joint_Letter_arrest_Hasan_KOSOVO.pdf\" target=\"_blank\">carta de la FITIM, la FITTVC y la ICEM aqu\u00ed<\/a>.<\/p>","protected":false},"featured_media":0,"template":"","class_list":["post-199175","archive_imf","type-archive_imf","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado - industriall-union<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado\" \/>\n<meta property=\"og:description\" content=\"SERBIA\/KOSOVO: Tras pasar 28 d\u00edas en la c\u00e1rcel, primero aislado y luego en una celda con otros 15 presos, Hasan Abazi, presidente del Sindicato Independiente de Trabajadores Metal\u00fargicos de Kosovo, afiliado a la FITIM, fue liberado el 20 de abril, a mediod\u00eda, previo pago de una fianza de 20.000 \u20ac. El presidente del sindicato, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/\" \/>\n<meta property=\"og:site_name\" content=\"industriall-union\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T08:33:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/\",\"url\":\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/\",\"name\":\"El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado - industriall-union\",\"isPartOf\":{\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\"},\"datePublished\":\"2012-04-23T17:03:00+00:00\",\"dateModified\":\"2025-01-31T08:33:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archive Imf\",\"item\":\"https:\/\/admin.industriall-union.org\/fr\/archive\/imf\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/admin.industriall-union.org\/fr\/#website\",\"url\":\"https:\/\/admin.industriall-union.org\/fr\/\",\"name\":\"industriall-union\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado - industriall-union","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/","og_locale":"es_ES","og_type":"article","og_title":"El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado","og_description":"SERBIA\/KOSOVO: Tras pasar 28 d\u00edas en la c\u00e1rcel, primero aislado y luego en una celda con otros 15 presos, Hasan Abazi, presidente del Sindicato Independiente de Trabajadores Metal\u00fargicos de Kosovo, afiliado a la FITIM, fue liberado el 20 de abril, a mediod\u00eda, previo pago de una fianza de 20.000 \u20ac. El presidente del sindicato, que [&hellip;]","og_url":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/","og_site_name":"industriall-union","article_modified_time":"2025-01-31T08:33:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/","url":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/","name":"El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado - industriall-union","isPartOf":{"@id":"https:\/\/admin.industriall-union.org\/fr\/#website"},"datePublished":"2012-04-23T17:03:00+00:00","dateModified":"2025-01-31T08:33:07+00:00","breadcrumb":{"@id":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/admin.industriall-union.org\/es\/archive\/imf\/el-presidente-del-sindicato-de-kosovo-encarcelado-hasan-abazi-liberado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/admin.industriall-union.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Archive Imf","item":"https:\/\/admin.industriall-union.org\/fr\/archive\/imf\/"},{"@type":"ListItem","position":3,"name":"El presidente del sindicato de Kosovo encarcelado, Hasan Abazi, liberado"}]},{"@type":"WebSite","@id":"https:\/\/admin.industriall-union.org\/fr\/#website","url":"https:\/\/admin.industriall-union.org\/fr\/","name":"industriall-union","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/admin.industriall-union.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/archive_imf\/199175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/archive_imf"}],"about":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/types\/archive_imf"}],"wp:attachment":[{"href":"https:\/\/admin.industriall-union.org\/es\/wp-json\/wp\/v2\/media?parent=199175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}